{"id":6272,"date":"2025-08-04T17:33:38","date_gmt":"2025-08-04T15:33:38","guid":{"rendered":"https:\/\/pigyki.fr\/?p=6272"},"modified":"2025-08-04T17:33:39","modified_gmt":"2025-08-04T15:33:39","slug":"um-olhar-sobre-a-minha-carreira-1979-2023","status":"publish","type":"post","link":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/","title":{"rendered":"Um olhar sobre a minha carreira 1979\/2023"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Comecei em abril de 1979 na cidade de Paris como \u201cMa\u00eetre D\u00e9l\u00e9gu\u00e9 \u00e0 l\u2019\u00c9ducation Musicale\u201d (Mestre Delegado para a Educa\u00e7\u00e3o Musical) em escolas infantis e prim\u00e1rias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aposentei-me oficialmente em 1\u00ba de julho de 2020, ap\u00f3s 41 anos de carreira, prolongada por 3 anos como trabalhador independente ao servi\u00e7o da Rym\u00e9a, o que perfaz um total de 44 anos de atividade profissional como professor de educa\u00e7\u00e3o musical segundo o \u201cM\u00e9todo Willems\u201d, que pratiquei desde o meu primeiro ano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m dirigi a Rym\u00e9a durante 29 anos, de 1991 a 2020, tendo sido sempre o professor principal desde a sua cria\u00e7\u00e3o por Jacques Chapuis, sob a \u00e9gide da AIEM Willems, em 1987.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apresentarei aqui quatro balan\u00e7os:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>da minha atividade pedag\u00f3gica com crian\u00e7as e adultos,<\/li>\n\n\n\n<li>da minha gest\u00e3o como diretor da Rym\u00e9a,<\/li>\n\n\n\n<li>da minha atividade como formador,<\/li>\n\n\n\n<li>do meu envolvimento no Movimento Willems<sup>\u00ae<\/sup>.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Balan\u00e7o como professor de educa\u00e7\u00e3o musical e piano<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 bastante misto.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>No que diz respeito \u00e0 inicia\u00e7\u00e3o musical at\u00e9 \u00e0 introdu\u00e7\u00e3o da solfeja<\/strong>, adquiri uma grande experi\u00eancia e at\u00e9 mesmo um profundo conhecimento dos 4 graus Willems<sup>\u00ae<\/sup>, reconhecido pelos meus pares em Fran\u00e7a e no estrangeiro.<br>Tamb\u00e9m intervim regularmente em creches durante cerca de 15 anos.<br>Ao longo da minha carreira, fiz perguntas a mim mesmo e procurei respostas, experimentando diferentes processos para concretizar os princ\u00edpios de cada grau.<br>Fiz muitos planos, quadros, programas, que eram sempre pontos de etapa que sempre compartilhei, principalmente com meus colegas e amigos de Paris e Barcelona.<br><br>Mas, ao contr\u00e1rio das fichas de s\u00edntese por graus de Jacques Chapuis, usei pouco as minhas ao longo do tempo e, em particular, nunca quis fix\u00e1-las em cadernos para os alunos, muito menos em livros. Porque a repeti\u00e7\u00e3o sempre me aborreceu.<br>Isso levou-me a seguir, na maioria das vezes, a minha intui\u00e7\u00e3o do momento, adaptando-me a cada aluno, a cada grupo e a cada aula. Por sorte, tinha uma intui\u00e7\u00e3o muito boa do que era necess\u00e1rio fazer com cada um no momento. A dificuldade estava em antecipar o material necess\u00e1rio para o progresso, especialmente para a solfejo.<br><br>Criei e realizei fichas de aula desde o meu in\u00edcio na Escola Nacional de M\u00fasica de Creuse, de 1983 a 1986, personalizadas para cada grupo durante muitos anos, depois retomadas e adaptadas ao longo da minha carreira.<br><br><\/li>\n\n\n\n<li><strong>No que diz respeito \u00e0 solfejo<\/strong>, n\u00e3o levei meus alunos a n\u00edveis avan\u00e7ados.<br>Por um lado, quando eles estavam motivados e se esfor\u00e7avam, eu os encaminhava para o Conservat\u00f3rio Regional, onde eles ingressavam e se adaptavam sem dificuldade.<br>Por outro lado, o livro de solfejo de Willems<sup>\u00ae<\/sup> era para mim um obst\u00e1culo pouco adequado ao desenrolar das aulas e \u00e0 progress\u00e3o. No entanto, tentei muito, pois todas as melodias que ele cont\u00e9m s\u00e3o interessantes, mas mesmo em 5 anos, j\u00e1 que ele deve ser usado durante 5 anos, nenhum dos meus alunos leu e estudou todas elas.<br>Foi tamb\u00e9m por isso que fiz fichas de trabalho para meus alunos.<br><br>Al\u00e9m disso, no livro Willems<sup>\u00ae<\/sup> praticamente n\u00e3o h\u00e1 material proposto para o 3\u00ba grau, mas sim sugest\u00f5es para desenvolver por conta pr\u00f3pria, o que eu fiz bastante (e compartilhei). Entre outras coisas, n\u00e3o h\u00e1 nenhum desenvolvimento sobre os pontos de refer\u00eancia, embora sejam um complemento indispens\u00e1vel \u00e0 leitura relativa e que requerem pr\u00e1tica durante os primeiros anos de solfejo. No 3\u00ba grau, pouco mais se pode fazer do que apresent\u00e1-los.<br><br>Lamento tamb\u00e9m a aus\u00eancia da clave de Do (Ut) nas primeiras leituras do livro, embora se possa utilizar as leituras \u201crelativas\u201d determinando uma clave. A liga\u00e7\u00e3o t\u00e3o clara que Willems<sup>\u00ae<\/sup> apresenta entre as claves no livro de solfejo do professor n\u00e3o encontra, infelizmente, qualquer eco no livro de solfejo do aluno. Mas questionar este manual sempre foi impens\u00e1vel, tanto mais que a sua difus\u00e3o serve os interesses da \u00c9ditions Pro Musica.<br><br><\/li>\n\n\n\n<li><strong>No que diz respeito aos primeiros passos no piano<\/strong>, tamb\u00e9m adquiri uma grande experi\u00eancia desenvolvendo sempre simultaneamente cada um dos quatro cap\u00edtulos preconizados por Willems<sup>\u00ae<\/sup>: o jogo de ouvido, o jogo\u00a0<em>a prima vista<\/em>, o jogo de mem\u00f3ria e o jogo improvisado.<br>Um dos meus objetivos era torn\u00e1-los aut\u00f4nomos na leitura antes de entrarem no ensino m\u00e9dio.<br>Tamb\u00e9m pratiquei muito a improvisa\u00e7\u00e3o a partir do teclado e, paralelamente, solfejei antes de tocar.<br>O jogo de ouvido, muitas vezes limitado ao primeiro ano, foi para mim e para os meus alunos o laborat\u00f3rio da polifonia, atrav\u00e9s da inven\u00e7\u00e3o de segundas vozes e da harmonia, atrav\u00e9s da pesquisa de acordes e cad\u00eancias adequados \u00e0s can\u00e7\u00f5es.<br><br>Jacques Chapuis me disse um dia que quando eu tivesse o mesmo prazer em dar aulas de piano que aulas de inicia\u00e7\u00e3o musical, eu teria realmente assimilado a mat\u00e9ria. Acredito, de fato, ter abordado todos os aspectos da quest\u00e3o e, al\u00e9m disso, ter conseguido transmitir o amor pelo piano \u00e0 maioria dos meus alunos. E assim que eles se tornavam aut\u00f4nomos na leitura, eu os confiava a pianistas mais experientes tecnicamente para abordar as grandes obras do repert\u00f3rio.<br><br><\/li>\n\n\n\n<li><strong>Quanto \u00e0 idade\u00a0e ao tipo de alunos<\/strong> que acompanhei, tive a sorte de trabalhar com todos os tipos:<\/li>\n<\/ol>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Crian\u00e7as muito pequenas em creches, de 18 meses a 3 anos, e algumas experi\u00eancias com beb\u00eas de 4 a 12 meses.<\/li>\n\n\n\n<li>Crian\u00e7as da escola Montessori Tom Pouce de Lyon, do jardim de inf\u00e2ncia ao ensino fundamental, durante 10 anos.<\/li>\n\n\n\n<li>Crian\u00e7as da Ma\u00eetrise da Catedral St-Jean de Lyon durante 6 anos, do 3\u00ba ano do ensino fundamental ao 6\u00ba ano, al\u00e9m do 7\u00ba e 8\u00ba ano durante um ano.<\/li>\n\n\n\n<li>Crian\u00e7as com defici\u00eancia mental em aulas individuais, incluindo um autista por quase 20 anos.<\/li>\n\n\n\n<li>Adultos de todas as idades, em aulas coletivas de solfejo, individuais de piano (incluindo o meu querido Patrice durante 30 anos!) e em canto coral tamb\u00e9m durante cerca de trinta anos&#8230;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Balan\u00e7o como Diretor da Rym\u00e9a<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m aqui, o balan\u00e7o \u00e9 misto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por um lado, posso orgulhar-me de ter dirigido esta escola durante 29 anos, aumentando progressivamente o n\u00famero de alunos, que passou de uma centena no in\u00edcio para 260 antes da pandemia da COVID.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por outro lado, penso que fui mais um coordenador do que um diretor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Primeiro por for\u00e7a das circunst\u00e2ncias, j\u00e1 que quando assumi a dire\u00e7\u00e3o pedag\u00f3gica, sucedendo a Jacques Chapuis, eu \u201cdirigia\u201d meus colegas, que tamb\u00e9m eram meus amigos: Jean-Dominique, depois Elisabeth, Jean-Marc e Nicole B. O nosso quinteto funcionava na perfei\u00e7\u00e3o (\u201cfingers in the nose\u201d, dizia o meu querido Jean-Dom!), e todos arrega\u00e7aram as mangas para superar as dificuldades econ\u00f3micas quando estas surgiram (concertos, obras de insonoriza\u00e7\u00e3o, redu\u00e7\u00e3o de sal\u00e1rios&#8230;).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00f3s nos v\u00edamos muito e eu fazia muitas reuni\u00f5es. No entanto, cada um trabalhava como queria, em seu canto, em coes\u00e3o com a equipe pelo simples fato de que todos \u00e9ramos formados pela Willems\u00ae e todos ministr\u00e1vamos aulas de inicia\u00e7\u00e3o, solfejo e instrumentos (exceto Jean-Dominique). Este \u00e9 um ponto fundamental, pois a liga\u00e7\u00e3o entre estas duas \u00e1reas era natural e fluida, e a prepara\u00e7\u00e3o dos dois concertos anuais (Natal e fim de ano) e dos est\u00e1gios de Todos os Santos ou da primavera nos uniu ainda mais. \u00c9ramos criativos e complementares. <br><br>Com Nicole, toc\u00e1vamos muito a quatro m\u00e3os no piano, estimulados pela perspectiva do concerto anual dos professores.<br>Como esquecer o ciclo das 16 valsas de Johannes Brahms?\u2026<br>Tamb\u00e9m gravamos juntos mais de 50 can\u00e7\u00f5es para nossos alunos, cantando a duas vozes e acompanhando-nos ao piano a quatro m\u00e3os, improvisando nossas harmoniza\u00e7\u00f5es, trabalhadas, mas n\u00e3o escritas.<br>Nossos la\u00e7os de amizade com todos continuam, e ainda mantemos contato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um per\u00edodo aben\u00e7oado da minha carreira!\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando eles partiram, fui obrigado a assumir efetivamente a fun\u00e7\u00e3o de diretor, mas n\u00e3o mudei realmente minha rela\u00e7\u00e3o com os professores, que sempre considerei mais como colegas e colaboradores do que como subordinados, tanto mais que eu sempre dava entre 25 e 35 horas de aula por semana, ou seja, muito mais do que o dobro de cada um dos meus colegas na Rym\u00e9a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O problema \u00e9 que se tornava cada vez mais dif\u00edcil recrutar professores diplomados Willems<sup>\u00ae<\/sup>, especialmente para o ensino instrumental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando quis impor uma colabora\u00e7\u00e3o transversal mais ativa, nomeadamente para criar la\u00e7os que se tornaram muito insuficientes entre a solfeja e o instrumento, contando com as grava\u00e7\u00f5es de v\u00eddeo que cada um podia fazer durante as suas aulas, bati com a cabe\u00e7a na parede e deparei-me com a obstru\u00e7\u00e3o, inicialmente latente e depois conflituosa, de dois professores que eu tinha contratado jovens e sem experi\u00eancia e depois formado at\u00e9 ao Diploma Willems<sup>\u00ae<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para mim, isso \u00e9 um fracasso e um grande pesar. Pois ambos t\u00eam muitas qualidades e poderiam ter continuado a se desenvolver na Rym\u00e9a. Talvez precisassem \u201cmatar o pai\u201d para se libertar e al\u00e7ar voo? Desejo-lhes, de qualquer forma, felicidades em seu trabalho pedag\u00f3gico e musical&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, ap\u00f3s minha aposentadoria oficial como diretor, assegurei uma transi\u00e7\u00e3o de tr\u00eas anos com meu sucessor, como trabalhador independente, respondendo diariamente \u00e0s suas in\u00fameras perguntas, dando as aulas que ele me pedia, valorizando seu projeto junto ao Conselho Administrativo e deixando-lhe total liberdade. Era ele quem recrutava os professores e elaborava os hor\u00e1rios.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><em>Fim triste<\/em><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Infelizmente, ele se comportou comigo com profunda ingratid\u00e3o, acusando-me de querer sabotar a Rym\u00e9a ap\u00f3s minha sa\u00edda pelo simples fato de ter recuperado o material de som que me pertencia, o que, segundo ele, era equivalente a roubo!<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>O pior \u00e9 que ele foi apoiado em suas acusa\u00e7\u00f5es pelo presidente em exerc\u00edcio da Rym\u00e9a, pelo meu colega das aulas de forma\u00e7\u00e3o Willems<sup>\u00ae<\/sup> e pela presidente da FIW, apesar de serem colaboradoras e amigas h\u00e1 40 anos&#8230; Quando teria sido t\u00e3o simples falar comigo imediatamente, ele esperou dois meses para apresentar as suas acusa\u00e7\u00f5es, recusando a minha proposta de lhe oferecer o meu equipamento de som para resolver o conflito, e depois cortou toda a comunica\u00e7\u00e3o, protegido pelas suas \u201cmadrinhas\u201d que, por sua vez, me acusaram de inten\u00e7\u00f5es que n\u00e3o tinham nada a ver&#8230;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Que pena, e que baixaria&#8230;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Essas acusa\u00e7\u00f5es me deixaram arrasado, e ainda estou lutando para me recuperar, dois anos depois&#8230;<\/em><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3. Balan\u00e7o como formador no Diploma Willems<sup>\u00ae<\/sup><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Desde 2007, ap\u00f3s a morte de Jacques Chapuis, dei aulas para a forma\u00e7\u00e3o de professores em Paris, Lyon, depois em Liubliana (Eslov\u00eania) e Medell\u00edn (Col\u00f4mbia).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 um trabalho muito diferente formar professores do que dar aulas e conduzir um processo de aprendizagem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eu gostava e temia essas aulas de forma\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gostei pelo contato com pessoas muito diferentes, sempre interessantes, com percursos m\u00faltiplos, perguntas pontuais, pertinentes, at\u00e9 mesmo desconcertantes, muito estimulantes para questionar tudo e justificar ou compreender melhor tal ou tal funcionamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Temia n\u00e3o estar \u00e0 altura dos desafios e sempre me senti um pouco complexado pelo meu modesto n\u00edvel de solfejo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Temia tamb\u00e9m pelo tempo necess\u00e1rio para preparar os textos, embora sempre tenha podido usar os textos de Jacques Chapuis reunidos principalmente por Eul\u00e0lia, que forneceu e compartilhou com a equipe de formadores ativos um trabalho not\u00e1vel pelo qual \u00e9 pouco reconhecida. Que ela seja aqui mais uma vez agradecida: OBRIGADO, EUL\u00c0LIA!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O mais importante na minha prepara\u00e7\u00e3o era o hor\u00e1rio que constitu\u00eda o meu plano de aulas.<br>Porque dar 11 a 12 horas de aula em 2 dias num ambiente fechado (numa cave em Paris!) \u00e9 uma prova\u00e7\u00e3o, tanto para o formador como para os alunos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, nunca li uma aula. As minhas \u00fanicas notas eram o meu hor\u00e1rio, mais ou menos cronometrado, e os textos das leituras e ditados. Uma vez iniciado o cap\u00edtulo, sabia o que fazer e raramente me repetia.<br>O mais dif\u00edcil para mim era desenvolver os temas das disserta\u00e7\u00f5es, que tinha de preparar longamente, e corrigir as inven\u00e7\u00f5es mel\u00f3dicas e harm\u00f3nicas (a duas vozes).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meu ponto forte sempre foi a pedagogia pr\u00e1tica, com a observa\u00e7\u00e3o de v\u00eddeos e seus coment\u00e1rios.<br>Evolui muito nesse aspecto ao longo do tempo. No in\u00edcio, eu podia ser severo (como Jacques Chapuis costumava ser) e certamente desajeitado (o que \u00e9 quase uma marca registrada!). Mas acredito que, no fundo, nunca julguei ningu\u00e9m e fiz uma distin\u00e7\u00e3o clara entre o que via ser feito, mais ou menos bem, e a pessoa que o fazia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 a coisa mais importante que aprendi com Jacques Chapuis: distinguir entre o \u201cn\u00e3o pessoal\u201d, neutro e impessoal, o \u201cpessoal\u201d, que diz respeito ao ser, e o \u201ctranspessoal\u201d, que transcende a pessoa, que \u00e9 ent\u00e3o apenas o ve\u00edculo de princ\u00edpios mais gerais. Encontramos um pouco dessas distin\u00e7\u00f5es com o \u201csaber \u201d, o \u201csaber fazer\u201d e o \u201csaber estar\u201d, embora n\u00e3o estejam correlacionados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, se alguma vez disse a algu\u00e9m que a sua aula era \u201cnula\u201d, e infelizmente isso aconteceu (fui criticado e n\u00e3o perdoado!), nunca pensei que essa pessoa fosse nula: era a sua pr\u00e1tica que eu estava a qualificar. Mas n\u00e3o me apercebia que isso n\u00e3o era aceit\u00e1vel para a pessoa em quest\u00e3o devido \u00e0 minha forma, por vezes perempt\u00f3ria, de lho dizer.<br>Creio que, neste aspeto, melhorei bastante ao longo do tempo, o que me permitiu acompanhar melhor os meus alunos\/professores&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Continuo muito cr\u00edtico em rela\u00e7\u00e3o ao programa de forma\u00e7\u00e3o do Diploma Willems<sup>\u00ae<\/sup>, embora em 2020\/21, com a minha ex-colega, o nosso trabalho de reformula\u00e7\u00e3o em 2 Diplomas, cada um com 2 anos (em vez de 3), seja um avan\u00e7o not\u00e1vel.<br>Penso que os n\u00edveis exigidos em solfejo, harmonia e piano s\u00e3o demasiado elevados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Compreendo o desejo de \u201cexcel\u00eancia\u201d defendido pela presidente da FIW, no sentido de que devemos dar o melhor de n\u00f3s mesmos \u00e0s crian\u00e7as.<br>O problema \u00e9 que essa exig\u00eancia se traduz numa sele\u00e7\u00e3o elitista que \u00e9 o oposto da filosofia de Willems<sup>\u00ae<\/sup>, que concebeu tr\u00eas n\u00edveis de forma\u00e7\u00e3o pedag\u00f3gica para se dirigir a todos os n\u00edveis de professores: o Certificado, o Diploma Pedag\u00f3gico e o Diploma Did\u00e1tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa \u00e9 uma das raz\u00f5es que me levaram a deixar esse Movimento internacional que, no entanto, animou minha vida por mais de 40 anos&#8230;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4. Balan\u00e7o do meu envolvimento no Movimento Willems<sup>\u00ae<\/sup><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Membro desde 1981, diplomado em 1982, tornei-me uma esp\u00e9cie de assistente-colaborador de Jacques Chapuis desde a cria\u00e7\u00e3o da Rym\u00e9a em Lyon, em 1987.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inicialmente, participei nas forma\u00e7\u00f5es em Lyon e Paris, realizando avalia\u00e7\u00f5es individuais e aulas coletivas de apoio.<br>Depois, substitu\u00ed Jacques ocasionalmente nas aulas, principalmente em Paris.<br>Como a minha esposa Lylian se tornou coordenadora dos Congressos durante 3 anos, tamb\u00e9m participei ativamente na sua organiza\u00e7\u00e3o log\u00edstica desde 1984, em Lyon.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 2007, com a morte inesperada de Jacques Chapuis (na sequ\u00eancia de uma opera\u00e7\u00e3o&nbsp;<em>a priori<\/em>&nbsp;benigna), nada estava previsto para a sua sucess\u00e3o, nem mesmo o acompanhamento das atividades da AIEM Willems. Assegurei a transi\u00e7\u00e3o na Fran\u00e7a, com o tesoureiro Romain Cottreaux, at\u00e9 o Congresso de Ljubljana, em 2008, na Eslov\u00eania, quando fui impulsionado e eleito presidente do Movimento Internacional Willems, contra todas as minhas expectativas pessoais.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><em>Presidente do Movimento Internacional Willems<\/em><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Assumi esta fun\u00e7\u00e3o durante 4 anos, de 2008 a 2012, durante os quais trabalhei muito para fazer as coisas evolu\u00edrem.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Profissionalizei os formadores, declarando-os como professores, quando eles tinham apenas o estatuto de \u201cestudantes bolsistas\u201d.<\/li>\n\n\n\n<li>Propus e redigi em grande parte novos estatutos que transformaram a AIEM na Federa\u00e7\u00e3o Internacional Willems\u00ae.<\/li>\n\n\n\n<li>Registei o nome \u201cWillems\u00ae\u201d como marca associada ao seu m\u00e9todo na Fran\u00e7a e no mundo, para valorizar o seu conte\u00fado e evitar desvios ou apropria\u00e7\u00f5es indevidas.<\/li>\n\n\n\n<li>Propus uma reativa\u00e7\u00e3o da vertente \u201cpedagogia pr\u00e1tica\u201d na forma\u00e7\u00e3o para o Diploma atrav\u00e9s de v\u00eddeos a serem realizados pelos alunos com os seus alunos. Apesar da forte resist\u00eancia e in\u00e9rcia dos meus colegas formadores no in\u00edcio (durante pelo menos 5 anos), esta parte da forma\u00e7\u00e3o tornou-se t\u00e3o importante quanto a pedagogia fundamental e a musicalidade, o que me deixa muito satisfeito.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Acreditei que alterar os estatutos permitiria ao Movimento Willems\u00ae desenvolver-se a n\u00edvel internacional. N\u00e3o consegui. Este Movimento continua a ser um pequeno nicho cujos membros ativos defendem, em \u00faltima an\u00e1lise, apenas os seus interesses e a sua zona de influ\u00eancia. Raros s\u00e3o aqueles que trabalham realmente pelo interesse geral e, quando o fazem, em Fran\u00e7a, \u00e9 para elevar o n\u00edvel da forma\u00e7\u00e3o, como para justificar o seu interesse&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estes quatro anos de presid\u00eancia foram os mais dif\u00edceis da minha vida profissional. Eu resisti, mas a que pre\u00e7o: fui chamado de usurpador, obrigado a engolir sapos, prejudicado, tra\u00eddo&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s minha presid\u00eancia da FIW, ocupei sucessivamente quase todas as fun\u00e7\u00f5es no Conselho de Administra\u00e7\u00e3o, com mais ou menos efic\u00e1cia: secret\u00e1rio, respons\u00e1vel pela forma\u00e7\u00e3o, respons\u00e1vel pelo CAP, tesoureiro.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><em>Webmaster<\/em><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Em 2008, reativei o site e o desenvolvi com a ajuda de uma amiga, em 7 idiomas.<br>Essa dimens\u00e3o multil\u00edngue era muito importante para mim, para que cada membro fosse levado em considera\u00e7\u00e3o, se reconhecesse no site e pudesse divulg\u00e1-lo ao seu redor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 2020, recriei completamente o site com a ajuda de um sobrinho, criando um site muito grande (grande demais?!) em 5 idiomas, com um total de mais de 600 p\u00e1ginas e artigos, um boletim informativo mensal, um banco de dados para os alunos em forma\u00e7\u00e3o com os v\u00eddeos dos 2 anos completos da nova f\u00f3rmula de forma\u00e7\u00e3o (160 horas de aulas), e muito mais&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trabalhei neste site durante milhares de horas, disponibilizando gratuitamente \u00e0 FIW uma ferramenta de comunica\u00e7\u00e3o muito completa, que \u00e9 ao mesmo tempo uma refer\u00eancia na apresenta\u00e7\u00e3o da pedagogia Willems\u00ae e um banco de dados para os alunos em forma\u00e7\u00e3o, bem como para os membros diplomados. Solicitei ao Conselho Administrativo em todas as reuni\u00f5es que alimentassem este site com suas pr\u00f3prias publica\u00e7\u00f5es, mas foi em v\u00e3o! Eu era praticamente o \u00fanico redator dos artigos apresentados, o que n\u00e3o era meu objetivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s minha demiss\u00e3o do Conselho Administrativo durante o Congresso de Udine em 2023, insisti para que o Conselho criasse uma comiss\u00e3o de reda\u00e7\u00e3o\/comunica\u00e7\u00e3o. Ela foi criada, mas nunca me contatou. Acabei desistindo de cuidar desse site que aparentemente n\u00e3o interessava a ningu\u00e9m.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele foi confiado a um prestador de servi\u00e7os pago, que apresentou um modelo no m\u00eas seguinte. Mas ele s\u00f3 foi aprovado um ano depois, para anunciar o Congresso de 2025, reduzido a tr\u00eas idiomas. Toda a parte interativa e o banco de dados de v\u00eddeos desapareceram.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que pena.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><em>Congressos internacionais<\/em><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Elaborei os planos dos \u00faltimos Congressos de 2012 a 2023: 2012 em Lausanne (Su\u00ed\u00e7a), 2022 em Salvador-Bahia (Brasil) e 2023 em Udine (It\u00e1lia), e participei em todos os Congressos desde 2008.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><em>Experi\u00eancia no estrangeiro<\/em><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Trabalhar no exterior foi uma oportunidade incr\u00edvel: pude constatar a dimens\u00e3o universal da proposta de Willems\u00ae e relativizar pr\u00e1ticas que, \u00e0s vezes, s\u00f3 se justificavam pelo fato de que \u201cJacques fazia assim\u201d. O fato de ter que reformular os princ\u00edpios de trabalho para facilitar as tradu\u00e7\u00f5es me obrigou a sempre voltar aos textos de Edgar Willems.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E, claro, descobrir culturas t\u00e3o diferentes como as da Col\u00f4mbia e da Eslov\u00eania, e finalmente do Brasil, me enriqueceu consideravelmente e me permitiu avaliar as qualidades de cada uma, que muitas vezes faltam na Fran\u00e7a, nomeadamente o empenho dos professores, t\u00e3o not\u00e1vel na Col\u00f4mbia sob a impuls\u00e3o de Diana Franco em Medell\u00edn.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclus\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tive a grande sorte de fazer praticamente toda a minha carreira no mesmo lugar, na Rym\u00e9a, durante 36 anos, com total liberdade e independ\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me dediquei totalmente ao meu trabalho, \u00e0s vezes em detrimento dos meus filhos. Por isso, aconselho aos meus jovens colegas que sejam vigilantes nesse aspecto para n\u00e3o se arrependerem mais tarde&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gostei muito do meu trabalho e me considerei mais um artista pedagogo do que um m\u00fasico, embora n\u00e3o tenha vergonha das minhas composi\u00e7\u00f5es de can\u00e7\u00f5es e contos musicais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pois o que sempre me motivou foram as rela\u00e7\u00f5es humanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A proposta pedag\u00f3gica de Edgar Willems, baseada na natureza humana, tomando a educa\u00e7\u00e3o musical como ve\u00edculo privilegiado para uma educa\u00e7\u00e3o humanista e criativa, permitiu-me uma vida profissional rica e variada, incluindo muitas viagens, nomeadamente \u00e0 Col\u00f4mbia e \u00e0 Eslov\u00e9nia, mas tamb\u00e9m a Portugal, M\u00e9xico, Espanha, Su\u00ed\u00e7a, It\u00e1lia e, claro, na Fran\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As possibilidades de an\u00e1lise e diagn\u00f3stico evidenciadas por Willems\u00ae permitiram-me responder \u00e0s minhas in\u00fameras perguntas, o que me deu a impress\u00e3o de ter resposta para tudo. At\u00e9 costumava dizer aos meus filhos que estava cansado de estar sempre certo! Na verdade, nunca acreditei deter qualquer verdade. Questionava-me constantemente sobre a validade do que fazia e, sem parar, revisava o meu trabalho. Este balan\u00e7o \u00e9 mais um testemunho disso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saindo hoje dessa bolha willemsiana, descubro quase com espanto que h\u00e1 outras coisas na vida!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E, al\u00e9m do meu site e das pesquisas musicais que o alimentam, a aposentadoria me oferece generosamente novas perspectivas fora da m\u00fasica&#8230;<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Retrospectiva dos 44 anos de carreira profissional de Christophe Lazerges na escola Rym\u00e9a e na Federa\u00e7\u00e3o Internacional Willems\u00ae.<\/p>\n","protected":false},"author":1,"featured_media":984,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"yes","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[271],"tags":[],"class_list":["post-6272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personnel-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Um olhar sobre a minha carreira 1979\/2023 - Pigyki<\/title>\n<meta name=\"description\" content=\"Retrospectiva dos 44 anos de carreira profissional de Christophe Lazerges na escola Rym\u00e9a e na Federa\u00e7\u00e3o Internacional Willems\u00ae.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Um olhar sobre a minha carreira 1979\/2023 - Pigyki\" \/>\n<meta property=\"og:description\" content=\"Retrospectiva dos 44 anos de carreira profissional de Christophe Lazerges na escola Rym\u00e9a e na Federa\u00e7\u00e3o Internacional Willems\u00ae.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Pigyki\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-04T15:33:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-04T15:33:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/12\/20230608_185030-scaled-e1703180408762.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1150\" \/>\n\t<meta property=\"og:image:height\" content=\"789\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pigyki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pigyki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/pt\\\/2025\\\/08\\\/04\\\/um-olhar-sobre-a-minha-carreira-1979-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/pt\\\/2025\\\/08\\\/04\\\/um-olhar-sobre-a-minha-carreira-1979-2023\\\/\"},\"author\":{\"name\":\"Pigyki\",\"@id\":\"https:\\\/\\\/pigyki.fr\\\/#\\\/schema\\\/person\\\/0c57b3ed8707391e1213001f02e0ef84\"},\"headline\":\"Um olhar sobre a minha carreira 1979\\\/2023\",\"datePublished\":\"2025-08-04T15:33:38+00:00\",\"dateModified\":\"2025-08-04T15:33:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/pt\\\/2025\\\/08\\\/04\\\/um-olhar-sobre-a-minha-carreira-1979-2023\\\/\"},\"wordCount\":3626,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/#\\\/schema\\\/person\\\/0c57b3ed8707391e1213001f02e0ef84\"},\"image\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/pt\\\/2025\\\/08\\\/04\\\/um-olhar-sobre-a-minha-carreira-1979-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20230608_185030-scaled-e1703180408762.jpg\",\"articleSection\":[\"Personnel\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/pt\\\/2025\\\/08\\\/04\\\/um-olhar-sobre-a-minha-carreira-1979-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/pt\\\/2025\\\/08\\\/04\\\/um-olhar-sobre-a-minha-carreira-1979-2023\\\/\",\"url\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/pt\\\/2025\\\/08\\\/04\\\/um-olhar-sobre-a-minha-carreira-1979-2023\\\/\",\"name\":\"Um olhar sobre a minha carreira 1979\\\/2023 - Pigyki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/pt\\\/2025\\\/08\\\/04\\\/um-olhar-sobre-a-minha-carreira-1979-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/pt\\\/2025\\\/08\\\/04\\\/um-olhar-sobre-a-minha-carreira-1979-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20230608_185030-scaled-e1703180408762.jpg\",\"datePublished\":\"2025-08-04T15:33:38+00:00\",\"dateModified\":\"2025-08-04T15:33:39+00:00\",\"description\":\"Retrospectiva dos 44 anos de carreira profissional de Christophe Lazerges na escola Rym\u00e9a e na Federa\u00e7\u00e3o Internacional Willems\u00ae.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/pt\\\/2025\\\/08\\\/04\\\/um-olhar-sobre-a-minha-carreira-1979-2023\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/pt\\\/2025\\\/08\\\/04\\\/um-olhar-sobre-a-minha-carreira-1979-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/pt\\\/2025\\\/08\\\/04\\\/um-olhar-sobre-a-minha-carreira-1979-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20230608_185030-scaled-e1703180408762.jpg\",\"contentUrl\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20230608_185030-scaled-e1703180408762.jpg\",\"width\":1150,\"height\":789},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/pt\\\/2025\\\/08\\\/04\\\/um-olhar-sobre-a-minha-carreira-1979-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/pigyki.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Um olhar sobre a minha carreira 1979\\\/2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pigyki.fr\\\/#website\",\"url\":\"https:\\\/\\\/pigyki.fr\\\/\",\"name\":\"Pigyki\",\"description\":\"C.L. al fine\",\"publisher\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/#\\\/schema\\\/person\\\/0c57b3ed8707391e1213001f02e0ef84\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pigyki.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/pigyki.fr\\\/#\\\/schema\\\/person\\\/0c57b3ed8707391e1213001f02e0ef84\",\"name\":\"Pigyki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Logo-CL.jpg\",\"url\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Logo-CL.jpg\",\"contentUrl\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Logo-CL.jpg\",\"width\":524,\"height\":586,\"caption\":\"Pigyki\"},\"logo\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Logo-CL.jpg\"},\"sameAs\":[\"http:\\\/\\\/pigyki.fr\"],\"url\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/author\\\/admin4451\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Um olhar sobre a minha carreira 1979\/2023 - Pigyki","description":"Retrospectiva dos 44 anos de carreira profissional de Christophe Lazerges na escola Rym\u00e9a e na Federa\u00e7\u00e3o Internacional Willems\u00ae.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Um olhar sobre a minha carreira 1979\/2023 - Pigyki","og_description":"Retrospectiva dos 44 anos de carreira profissional de Christophe Lazerges na escola Rym\u00e9a e na Federa\u00e7\u00e3o Internacional Willems\u00ae.","og_url":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/","og_site_name":"Pigyki","article_published_time":"2025-08-04T15:33:38+00:00","article_modified_time":"2025-08-04T15:33:39+00:00","og_image":[{"width":1150,"height":789,"url":"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/12\/20230608_185030-scaled-e1703180408762.jpg","type":"image\/jpeg"}],"author":"Pigyki","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pigyki","Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/#article","isPartOf":{"@id":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/"},"author":{"name":"Pigyki","@id":"https:\/\/pigyki.fr\/#\/schema\/person\/0c57b3ed8707391e1213001f02e0ef84"},"headline":"Um olhar sobre a minha carreira 1979\/2023","datePublished":"2025-08-04T15:33:38+00:00","dateModified":"2025-08-04T15:33:39+00:00","mainEntityOfPage":{"@id":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/"},"wordCount":3626,"commentCount":2,"publisher":{"@id":"https:\/\/pigyki.fr\/#\/schema\/person\/0c57b3ed8707391e1213001f02e0ef84"},"image":{"@id":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/12\/20230608_185030-scaled-e1703180408762.jpg","articleSection":["Personnel"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/","url":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/","name":"Um olhar sobre a minha carreira 1979\/2023 - Pigyki","isPartOf":{"@id":"https:\/\/pigyki.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/#primaryimage"},"image":{"@id":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/12\/20230608_185030-scaled-e1703180408762.jpg","datePublished":"2025-08-04T15:33:38+00:00","dateModified":"2025-08-04T15:33:39+00:00","description":"Retrospectiva dos 44 anos de carreira profissional de Christophe Lazerges na escola Rym\u00e9a e na Federa\u00e7\u00e3o Internacional Willems\u00ae.","breadcrumb":{"@id":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/#primaryimage","url":"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/12\/20230608_185030-scaled-e1703180408762.jpg","contentUrl":"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/12\/20230608_185030-scaled-e1703180408762.jpg","width":1150,"height":789},{"@type":"BreadcrumbList","@id":"https:\/\/pigyki.fr\/index.php\/pt\/2025\/08\/04\/um-olhar-sobre-a-minha-carreira-1979-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/pigyki.fr\/"},{"@type":"ListItem","position":2,"name":"Um olhar sobre a minha carreira 1979\/2023"}]},{"@type":"WebSite","@id":"https:\/\/pigyki.fr\/#website","url":"https:\/\/pigyki.fr\/","name":"Pigyki","description":"C.L. al fine","publisher":{"@id":"https:\/\/pigyki.fr\/#\/schema\/person\/0c57b3ed8707391e1213001f02e0ef84"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pigyki.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/pigyki.fr\/#\/schema\/person\/0c57b3ed8707391e1213001f02e0ef84","name":"Pigyki","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/06\/Logo-CL.jpg","url":"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/06\/Logo-CL.jpg","contentUrl":"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/06\/Logo-CL.jpg","width":524,"height":586,"caption":"Pigyki"},"logo":{"@id":"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/06\/Logo-CL.jpg"},"sameAs":["http:\/\/pigyki.fr"],"url":"https:\/\/pigyki.fr\/index.php\/author\/admin4451\/"}]}},"_links":{"self":[{"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/posts\/6272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/comments?post=6272"}],"version-history":[{"count":1,"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/posts\/6272\/revisions"}],"predecessor-version":[{"id":6273,"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/posts\/6272\/revisions\/6273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/media\/984"}],"wp:attachment":[{"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/media?parent=6272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/categories?post=6272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/tags?post=6272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}