{"id":4998,"date":"2025-05-04T23:23:27","date_gmt":"2025-05-04T21:23:27","guid":{"rendered":"https:\/\/pigyki.fr\/?page_id=4998"},"modified":"2025-07-12T23:07:37","modified_gmt":"2025-07-12T21:07:37","slug":"le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems","status":"publish","type":"page","link":"https:\/\/pigyki.fr\/index.php\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\/","title":{"rendered":"Le d\u00e9veloppement auditif et vocal"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Le d\u00e9veloppement de l&rsquo;oreille musicale et du chant dans l\u2019\u00e9ducation musicale Willems<sup>\u00ae<\/sup><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mateja Tomac Calligaris &#8211; M\u00e9moire Didactique Willems<sup>\u00ae<\/sup><\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Voici le m\u00e9moire r\u00e9dig\u00e9 en 2023 pour son Dipl\u00f4me Didactique Willems<sup>\u00ae<\/sup>&nbsp;par mon ancienne coll\u00e8gue&nbsp;<strong>Mateja Tomac-Calligaris<\/strong>. Elle avait r\u00e9dig\u00e9 son m\u00e9moire sur \u00ab\u00a0<strong><em>Le d\u00e9veloppement de l&rsquo;oreille musicale et du chant dans l\u2019\u00e9ducation musicale Willems<sup>\u00ae<\/sup><\/em><\/strong>\u00ab\u00a0. Elle a tr\u00e8s aimablement accept\u00e9 qu\u2019il soit publi\u00e9 ici et ainsi mis \u00e0 disposition des \u00e9tudiants et amateurs de p\u00e9dagogie musicale. Je l\u2019en remercie beaucoup !<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\"><em>Passez la souris sur les titres rouges de la Table des Mati\u00e8res et cliquez sur celui en surbrillance bleu pour acc\u00e9der directement au chapitre correspondant, et sur la fl\u00e8che en bas \u00e0 droite pour remonter en haut de la page.<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>Le d\u00e9veloppement de l&rsquo;oreille musicale et du chant dans l\u2019\u00e9ducation musicale Willems<\/strong><sup>\u00ae<\/sup><\/h3>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\">TABLE DES MATI\u00c8RES<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>INTRODUCTION<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"#vibration-acoustique\">La vibration acoustique et le son<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"#organe-physiologique\">L&rsquo;oreille comme organe physiologique<\/a><\/strong><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong><a href=\"#developpement-oreille-musicale\">LE D\u00c9VELOPPEMENT DE L\u2019OREILLE MUSICALE&nbsp;<\/a><\/strong>\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"#si-oui-comment\">Est-ce que l\u2019oreille musicale peut se d\u00e9velopper, et si oui, comment ?<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"#r\u00e9ceptivit\u00e9-sensorielle-auditive\">La r\u00e9ceptivit\u00e9 sensorielle auditive<\/a><\/strong>\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"#carillon-intratonal\"><em>L&rsquo;espace intratonal et le carillon intratonal<\/em><\/a><\/strong><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong><a href=\"#affectivit\u00e9-auditive\">L\u2019affectivit\u00e9 auditive<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"#intelligence-auditive\">L\u2019intelligence auditive<\/a><\/strong>\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"#solmisation-latine\"><em>Probl\u00e9matique de la solmisation latine compar\u00e9e \u00e0 l&rsquo;alphabet musical<\/em><\/a><\/strong><\/li>\n\n\n\n<li><strong><em><a href=\"#l'harmonie\">L&rsquo;harmonie<\/a><\/em><\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong><a href=\"#developpement-du-chant\">LE D\u00c9VELOPPEMENT DU CHANT<\/a><\/strong>\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"#fonctionnement-des-cordes-vocales\">Description simple du fonctionnement des cordes vocales<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"#relation-oreille-voix\">La relation entre l\u2019oreille et la voix<\/a><\/strong><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong><a href=\"#conclusion\">CONCLUSION<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>INTRODUCTION<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019oreille et la voix sont d\u2019une extr\u00eame importance pour chaque personne, surtout pour celles qui s\u2019occupent de la musique. <\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:38% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"497\" height=\"372\" src=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/Lreille-et-la-voix.jpg\" alt=\"\" class=\"wp-image-5002 size-full\" srcset=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/Lreille-et-la-voix.jpg 497w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/Lreille-et-la-voix-300x225.jpg 300w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/Lreille-et-la-voix-281x210.jpg 281w\" sizes=\"auto, (max-width: 497px) 100vw, 497px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">L\u2019oreille a une place particuli\u00e8re parmi les cinq sens&nbsp; de l\u2019\u00eatre humain puisque le son est per\u00e7u directement, \u00e0 distance, rapidement et qu\u2019il a un fort impact sur l\u2019homme. Du point de vue physiologique l\u2019oreille reste assez myst\u00e9rieuse et l\u2019\u00e9coute n\u2019est pas sa seule fonction.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 36%\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">L\u2019oreille, comme organe qui transforme les vibrations acoustiques &#8211; \u00e0 travers des m\u00e9canismes complexes &#8211; en sons dans le cerveau, est \u00e9troitement li\u00e9e \u00e0 la voix, le moyen d\u2019expression primaire de l\u2019\u00eatre humain. <\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"279\" height=\"156\" src=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/Enfant-oreilles-et-bouche-ouvertes.jpg\" alt=\"\" class=\"wp-image-5000 size-full\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Willems \u00e9tait centr\u00e9 surtout sur les principes de base de l&rsquo;\u00e9ducation musicale.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il d\u00e9fendait l\u2019approche qui prend en consid\u00e9ration l\u2019\u00eatre humain en sa totalit\u00e9, c\u2019est \u00e0 dire ses dimensions physique, affective et mentale, faisant partie d\u2019un tout comprenant un p\u00f4le mat\u00e9riel et un p\u00f4le spirituel. Cette trilogie correspond dans la musique au rythme, \u00e0 la m\u00e9lodie et \u00e0 l\u2019harmonie. La musique est l\u2019art des sons&nbsp;; le d\u00e9veloppement de l\u2019oreille musicale et de l\u2019expression musicale, surtout du chant, occupe la partie centrale de la pens\u00e9e willemsienne. Le d\u00e9veloppement auditif permet au musicien de d\u00e9velopper l\u2019image int\u00e9rieure du son, qui est la cl\u00e9 d\u2019une v\u00e9ritable musicalit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je vais donc me concentrer dans la suite de ce m\u00e9moire sur les principes p\u00e9dagogiques pr\u00e9conis\u00e9s par Willems pour le d\u00e9veloppement de l\u2019oreille musicale et du chant.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mon activit\u00e9 principale est la gestion d\u2019une \u00e9cole de musique qui couvre des domaines tr\u00e8s riches et vari\u00e9s. Suite \u00e0 mes nombreuses exp\u00e9riences dans ce champ de travail, je suis arriv\u00e9e \u00e0 la conviction qu\u2019il est tr\u00e8s important de ne jamais perdre de vue les bases du fonctionnement en musique \u2013 l\u2019oreille musicale et le chant. C\u2019est pourquoi j\u2019ai choisi d\u2019approfondir mes \u00e9tudes de ce sujet p\u00e9dagogique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je me limiterai surtout aux d\u00e9buts de l\u2019\u00e9ducation musicale et je pr\u00e9senterai les principes \u00e9l\u00e9mentaires du travail p\u00e9dagogique. J\u2019ajouterai quelques exp\u00e9riences et regards personnels aux pens\u00e9es de Willems. Mais tout d\u2019abord je vais pr\u00e9senter le ph\u00e9nom\u00e8ne du son et le m\u00e9canisme de base de la perception du son chez l\u2019homme.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" id=\"vibration-acoustique\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"LA-VIBRATION-ACOUSTIQUE\"><strong>LA VIBRATION ACOUSTIQUE ET LE SON<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le son est une sensation, qui est provoqu\u00e9e chez l\u2019homme ou l\u2019animal dot\u00e9 de l\u2019ou\u00efe, par la vibration de corps\/choses mat\u00e9rielles. Quand la vibration, propag\u00e9e dans l\u2019air ou un autre corps \u00e9lastique, atteint l\u2019oreille humaine, le sens de l\u2019ou\u00efe, qui c\u2019est reli\u00e9 au cerveau, cr\u00e9e en nous la sensation du son \u00e0 l\u2019aide d\u2019un m\u00e9canisme complexe dont je parlerai bri\u00e8vement plus tard. L\u2019ondulation elle-m\u00eame est un ph\u00e9nom\u00e8ne objectif, tandis que la sensation est subjective ; elle d\u00e9pend de la constitution de l\u2019organe auditif, des exp\u00e9riences sonores ant\u00e9rieures, de l\u2019int\u00e9r\u00eat pour le son, des connexions neuronales, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019ondulation sonore est d\u00e9finie surtout par la fr\u00e9quence et l\u2019amplitude de la vibration. D\u2019une mani\u00e8re br\u00e8ve et simplifi\u00e9e nous pouvons dire, que la hauteur du son d\u00e9pend de la fr\u00e9quence, tandis que le volume sonore est conditionn\u00e9 par l\u2019amplitude de l\u2019onde. Le timbre du son quant \u00e0 lui, est le r\u00e9sultat de la forme de l\u2019onde sonore. Du point de vue de sa production, le timbre du son d\u00e9pend de la construction et de la forme du corps qui \u00e9met les vibrations et de la mani\u00e8re par laquelle elles sont mises en mouvement, voire amplifi\u00e9es ; ces conditions ont aussi un impact sur la dur\u00e9e du son.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019oreille humaine capte les fr\u00e9quences entre 16 et 20.000 Hz, mais d\u2019une mani\u00e8re plus sensible entre 2.000 et 5.000 Hz ; en-dessous de la limite inf\u00e9rieure nous avons l\u2019infrason, au-dessus de la limite sup\u00e9rieure nous parlons de l\u2019ultrason. Les animaux de diff\u00e9rentes esp\u00e8ces ont des rayons de perception de son diff\u00e9rents.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour la musique nous utilisons les sons dans le cadre de fr\u00e9quences entre 65 et 8276 Hz.&nbsp;<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" id=\"organe-physiologique\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">L&rsquo;OREILLE COMME ORGANE PHYSIOLOGIQUE<\/h4>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">L\u2019oreille, organe destin\u00e9 \u00e0 la r\u00e9ception du son, joue un r\u00f4le important aussi dans le maintient de l\u2019\u00e9quilibre, la perception du corps dans l\u2019espace et le maintient de la posture du corps. Elle est compos\u00e9e de 3 parties : l\u2019oreille externe (1), moyenne (2) et interne (3).&nbsp;<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"876\" src=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-1024x876.png\" alt=\"\" class=\"wp-image-5011 size-full\" srcset=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-1024x876.png 1024w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-300x257.png 300w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-768x657.png 768w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-1536x1314.png 1536w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-281x240.png 281w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image.png 1728w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"488\" height=\"354\" src=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-1.png\" alt=\"\" class=\"wp-image-5012 size-full\" srcset=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-1.png 488w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-1-300x218.png 300w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-1-281x204.png 281w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-1-414x300.png 414w\" sizes=\"auto, (max-width: 488px) 100vw, 488px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">L\u2019oreille externe comprend le pavillon auriculaire (a), qui capte l\u2019ondulation sonore, et le conduit auditif (b), dont la longueur est d\u2019un peu plus de 2 cm et a fonction de r\u00e9sonateur. Le conduit auditif amplifie le mieux les sons des fr\u00e9quences propres au langage humain. L\u2019oreille externe est s\u00e9par\u00e9e de l\u2019oreille moyenne par le tympan (c), une membrane fibreuse \u00e9lastique, un tissu conjonctif.&nbsp;<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Les trois osselets sont les plus petits os du corps humain.<br>Assembl\u00e9s en cha\u00eene comme un fl\u00e9au, ils font partie de l\u2019oreille moyenne : le marteau (e), l\u2019enclume (f) et l\u2019\u00e9trier (d). Sont attach\u00e9s \u00e0 eux les plus petits muscles du corps humain, qui &#8211; par leur contraction et d\u00e9contraction &#8211; \u00e9quilibrent le volume du son transmis, soit en l\u2019amplifiant sous l\u2019effet du fl\u00e9au, soit en le r\u00e9duisant en inhibant les muscles qui permettent leurs mouvements.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le marteau est attach\u00e9 au tympan tandis que l\u2019\u00e9trier est fix\u00e9 \u00e0 la fen\u00eatre ovale (h) de la cochl\u00e9e (j), \u00e9quivalent d\u2019un tympan faisant partie de l\u2019oreille interne. Dans la partie de l\u2019oreille moyenne nous trouvons aussi la trompe d\u2019Eustache, qui relie l\u2019oreille \u00e0 l\u2019\u0153sophage. Elle permet de r\u00e9guler la pression de l\u2019air de l\u2019oreille moyenne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019oreille interne comprend l\u2019organe auditif, la cochl\u00e9e, tapiss\u00e9e de cellules cili\u00e9es, cellules nerveuses, et l\u2019organe de l\u2019\u00e9quilibre avec les trois canaux semi-circulaires.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainsi, les 3 parties de l\u2019oreille correspondent \u00e0 3 \u00e9tats de la vibration :<\/p>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<ul class=\"wp-block-list\">\n<li>elle se propage d\u2019abord dans l\u2019air, milieu gazeux, le pavillon jouant un premier r\u00f4le de concentration et d\u2019amplification<\/li>\n\n\n\n<li>dans l\u2019oreille moyenne, la vibration est transform\u00e9e et amplifi\u00e9e par le mouvement m\u00e9canique de la cha\u00eene des osselets ;<\/li>\n\n\n\n<li>enfin cette impulsion m\u00e9canique se transmet au milieu liquide de l\u2019oreille interne cr\u00e9ant une vague dans la cochl\u00e9e tapiss\u00e9e des cellules cill\u00e9es dont l\u2019ondulation plus ou moins forte cr\u00e9e un signal \u00e9lectrique que le nerf auditif transmet au cerveau.&nbsp;<\/li>\n<\/ul>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"544\" src=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-2.png\" alt=\"\" class=\"wp-image-5013 size-full\" srcset=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-2.png 800w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-2-300x204.png 300w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-2-768x522.png 768w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-2-281x191.png 281w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-3.png\" alt=\"\" class=\"wp-image-5014 size-full\" srcset=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-3.png 750w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-3-300x200.png 300w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-3-281x187.png 281w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Il est \u00e0 noter que les cellules cili\u00e9es sont fragiles.<br>Si la vague est trop violente, elles risquent d\u2019\u00eatre endommag\u00e9es, et ce de fa\u00e7on d\u00e9finitive, si le cerveau n\u2019a pas command\u00e9 aux muscles de la cha\u00eene des osselets de ne pas r\u00e9percuter une onde trop forte. On trouve dans ce cas des pertes d\u2019audition pour une utilisation inappropri\u00e9e d\u2019\u00e9couteurs coll\u00e9s aux oreilles\u2026<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Donc la vibration traverse le conduit auditif et arrive jusqu\u2019au tympan, qui oscille. L\u2019ondulation est transmise \u00e0 la cha\u00eene des osselets de l\u2019oreille moyenne. Vu la composition de l\u2019oreille moyenne, l\u2019intensit\u00e9 de la vibration est largement amplifi\u00e9e pour les fr\u00e9quences entre 1 et 10 kHz. La force m\u00e9canique amplifi\u00e9e est transform\u00e9e dans les signaux \u00e9lectriques, suite au choc contre le liquide de la cochl\u00e9e. Sur la membrane basilaire de celle-ci se situe l\u2019ensemble des cellules, fondamentales pour notre pr\u00e9hension et l\u2019analyse des vibrations,&nbsp; l\u2019organe de Corti, du nom de son d\u00e9couvreur Alphonse Corti. Ces cellules cili\u00e9es sont des transducteurs m\u00e9cano-\u00e9lectriques, qui transforment les mouvements des cils cellulaires en signaux \u00e9lectriques dans les cellules. Les signaux \u00e9lectriques traversent la cochl\u00e9e et continuent leur chemin \u00e0 travers le nerf auditif vers le cerveau, qui transforme enfin ce codage nerveux en une image appel\u00e9e SON !&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Ce n\u2019est que dans le cerveau que le SON est produit et analys\u00e9.&nbsp;<\/strong><br><strong>Toutes les \u00e9tapes ant\u00e9rieures ne v\u00e9hiculent que des VIBRATIONS.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est tr\u00e8s pr\u00e9cieux pour l\u2019\u00e9ducateur musical de bien conna\u00eetre ce fonctionnement physiologique de l\u2019oreille, car il ne peut agir pour favoriser le d\u00e9veloppement auditif de ses \u00e9l\u00e8ves que sur le fonctionnement de l\u2019oreille moyenne et sur le fonctionnement du cerveau dans son analyse du son.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En effet, la pr\u00e9sence de muscles inerv\u00e9s li\u00e9s \u00e0 la cha\u00eene des osselets signifie que le cerveau peut agir sur leur r\u00e9activit\u00e9. Comment ? En focalisant l\u2019attention, en \u00ab&nbsp;tendant l\u2019oreille&nbsp;\u00bb !<br>L\u2019\u00e9ducateur agit alors en donnant envie \u00e0 l\u2019\u00e9l\u00e8ve de tendre l\u2019oreille, \u00e0 s\u2019int\u00e9resser au son, voire m\u00eame \u00e0 aimer le son musical\u2026<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" id=\"developpement-oreille-musicale\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">LE D\u00c9VELOPPEMENT DE L\u2019OREILLE MUSICALE&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Willems a beaucoup parl\u00e9 de l\u2019oreille et du d\u00e9veloppement auditif. Pour pouvoir exprimer pleinement la synth\u00e8se de sa pens\u00e9e, il s\u2019est servi de l\u2019expression oreille musicale. L\u2019oreille musicale permet \u00e0 l\u2019\u00eatre humain la r\u00e9ception et la compr\u00e9hension de la musique. Dans cette conception aussi nous pouvons rencontrer la trilogie, qui repr\u00e9sente le fondement de la pens\u00e9e willemsienne, c&rsquo;est-\u00e0-dire : corps \u2013 \u00e9motions \u2013 pens\u00e9e. \u00c0 mon avis, la valeur inestimable de l\u2019\u0153uvre de Willems consiste dans l\u2019identification de ces trois \u00e9l\u00e9ments constitutifs de l\u2019\u00eatre humain, physique, affectif et mental, \u00e9tablissant une corr\u00e9lation avec les trois \u00e9l\u00e9ments constitutifs de la musique : le rythme, la m\u00e9lodie et l\u2019harmonie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vie physique et physiologique correspond \u00e0 la vie rythmique ;<br>la vie affective correspond \u00e0 la vie m\u00e9lodique ;<br>et la vie mentale correspond \u00e0 la vie harmonique.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Vie<\/strong><\/td><td><strong>Sensorielle<\/strong><\/td><td><strong>Affective<\/strong><\/td><td><strong>Mentale<\/strong><\/td><\/tr><tr><td><strong>Musique<\/strong><\/td><td><strong>Rythme<\/strong><\/td><td><strong>M\u00e9lodie<\/strong><\/td><td><strong>Harmonie<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dans sa conception de l\u2019oreille musicale, Willems a uni l\u2019oreille comme organe physiologique avec l\u2019oreille \u201cint\u00e9rieure\u201d, qui comprend toutes les fonctions mentales, reli\u00e9es aux contenus musicaux dans notre m\u00e9moire. Avec ces fonctions mentales, le musicien peut cr\u00e9er des images auditives int\u00e9rieures, qui sont la cl\u00e9 de la vraie musicalit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voil\u00e0 une des citations les plus connues de Willems :&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Les mauvais musiciens n\u2019entendent pas ce qu\u2019ils jouent ; les moyens auraient pu entendre, mais n\u2019\u00e9coutent pas ; ceux qui sont un peu meilleurs, entendent ce qu\u2019ils avaient jou\u00e9, mais seulement les bons musiciens entendent ce qu\u2019ils vont jouer.<\/em>\u201d <br>(Bases psychologiques de l\u2019\u00e9ducation musicale, chapitre IX \u2013 Audition int\u00e9rieure absolue et relative)<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" id=\"si-oui-comment\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">Est-ce que l\u2019oreille musicale peut se d\u00e9velopper, et si oui, comment ?&nbsp;<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Cette question est essentielle pour chaque p\u00e9dagogue musical.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Willems a \u00e9tabli ses principes p\u00e9dagogiques sur la conviction que cela est tout \u00e0 fait possible. \u00c0 travers les exp\u00e9riences qu\u2019il a accumul\u00e9 toute sa vie, il a pu confirmer cette conviction \u2013 il en parle tr\u00e8s largement dans ses \u0153uvres. Comme je l\u2019ai d\u00e9j\u00e0 mentionn\u00e9, l\u2019oreille n\u2019est pas seulement l\u2019organe sensoriel, mais comprend aussi les processus \u00e9motifs et mentaux, qui changent avec l\u2019\u00e9volution de l\u2019homme. Elle pr\u00e9sente un grand potentiel, dont on peut profiter plus pleinement si nous sommes guid\u00e9s par l\u2019int\u00e9r\u00eat pour la musique, la sensibilit\u00e9 affective et l\u2019intelligence.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On ne peut pas changer l\u2019organe auditif, mais on peut grandement en am\u00e9liorer le fonctionnement.<br>C\u2019est tout le sens du \u00ab&nbsp;d\u00e9veloppement auditif&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Willems dans ses \u0153uvres explique que la capacit\u00e9 globale de l\u2019\u00e9coute est conditionn\u00e9e par trois capacit\u00e9s plus sp\u00e9cifiques : la r\u00e9ceptivit\u00e9 sensorielle auditive \u2013 perception physiologique du son \u00e0 travers l\u2019oreille ; la sensibilit\u00e9 auditive \u2013 la r\u00e9action \u00e9motionnelle \u00e0 ce que l\u2019on \u00e9coute ; et l\u2019intelligence auditive \u2013 l\u2019\u00e9coute analytique, consciente. Dans ce sens nous pouvons utiliser trois expressions : ou\u00efr \u2013 \u00e9couter \u2013 entendre. Ces trois facult\u00e9s sont \u00e9videmment entrem\u00eal\u00e9es, mais chacune d\u2019elles comporte ses propres qualit\u00e9s et potentiel de d\u00e9veloppement.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le p\u00e9dagogue musical doit savoir comment d\u00e9velopper chaque domaine individuellement et aussi la capacit\u00e9 globale de l\u2019\u00e9coute, affect\u00e9e par d\u2019autres donn\u00e9es \u2013 caract\u00e9ristiques personnelles, culture musicale, relation de la personne avec le son et la musique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Willems dit que le musicien a une excellente capacit\u00e9 d\u2019\u00e9coute quand il per\u00e7oit nettement les informations sonores, venues \u00e0 lui de l\u2019ext\u00e9rieur, quand il r\u00e9agit \u00e0 ces informations \u00e9motivement et quand il est capable de rendre conscient ce qu\u2019il a entendu.&nbsp;<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" id=\"r\u00e9ceptivit\u00e9-sensorielle-auditive\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">La r\u00e9ceptivit\u00e9 sensorielle auditive&nbsp;<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9ceptivit\u00e9 sensorielle auditive nous permet d\u2019\u00e9tablir le contact avec le son et les ph\u00e9nom\u00e8nes sonores. C\u2019est une facult\u00e9 de l\u2019oreille qui reconna\u00eet et distingue diff\u00e9rentes qualit\u00e9s du son \u2013 timbre, intensit\u00e9, hauteur, mouvement sonore, harmoniques et ainsi de suite. La r\u00e9ceptivit\u00e9 sensorielle est notre moyen d\u2019utiliser le mat\u00e9riel sonore avec la sensibilit\u00e9 et l&rsquo;intelligence.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans son travail, Willems a clairement montr\u00e9 de fa\u00e7on empirique que la r\u00e9ceptivit\u00e9 sensorielle peut \u00eatre am\u00e9lior\u00e9e. Par l\u2019\u00e9ducation nous pouvons encourager, conduire et d\u00e9velopper le fonctionnement de l\u2019organe auditif.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le 4e chapitre de son livre \u00ab&nbsp;L\u2019oreille musicale&nbsp;\u00bb Willems cite Comenius, qui disait d\u00e9j\u00e0 en 1640 :<br><strong>\u201c<em>On ne trouve rien dans l&rsquo;intelligence qui n\u2019y soit arriv\u00e9 par les sens\u2026<\/em><\/strong><br><strong><em>L\u2019\u00e9l\u00e8ve doit apprendre \u00e0 conna\u00eetre les sons, qu\u2019il apprenne surtout \u00e0 utiliser ses sens\u2026<\/em>\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les cinq sens humains (vue, ou\u00efe, toucher, odorat et go\u00fbt) sont ceux qui rendent possible \u00e0 l\u2019homme le contact avec le monde qui l\u2019entoure. Chaque sens est un r\u00e9cepteur sp\u00e9cial \u00e0 la surface du corps, expos\u00e9 \u00e0 diff\u00e9rents impacts, venus de l\u2019environnement, diff\u00e9rents stimuli. Ce stimulus peut \u00eatre le toucher, la lumi\u00e8re, le son, des substances chimiques \u00e0 l\u2019\u00e9tat liquide ou gazeux, etc. Nous avons un r\u00e9cepteur diff\u00e9rent pour chacun de ces stimuli. Les sens repr\u00e9sentent donc une liaison entre l\u2019homme et son entourage. L\u2019homme est capable de percevoir ce que ses sens lui permettent ; il y a beaucoup d\u2019\u00e9l\u00e9ments objectifs qui restent en dehors de sa perception et bien s\u00fbr aussi de sa compr\u00e9hension.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;oreille est le r\u00e9cepteur du son chez l&rsquo;homme et elle se d\u00e9veloppe compl\u00e8tement pendant la gestation, lorsque l&rsquo;enfant reconna\u00eet d\u00e9j\u00e0 distinctement diff\u00e9rents sons et la voix des parents dans le ventre de la m\u00e8re. Tout de suite apr\u00e8s la naissance l\u2019enfant prend part \u00e0 l\u2019ambiant sonore soit en \u00e9coutant soit en \u00e9mettant ses propres sons et il \u00e9volue suivant les r\u00e9actions de son entourage.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Willems a reconnu l\u2019importance du d\u00e9veloppement de la r\u00e9ceptivit\u00e9 sensorielle dans la vie de tous les musiciens et y a consacr\u00e9 une grande partie de son travail. \u00c0 son \u00e9poque la r\u00e9ceptivit\u00e9 \u00e9tait la plupart du temps bien n\u00e9glig\u00e9e dans l\u2019\u00e9ducation musicale. M\u00eame aujourd\u2019hui elle n\u2019a souvent pas la place qu\u2019elle m\u00e9riterait dans les \u00e9coles de musique ; on la prend comme quelque chose qui va de soi ou bien on cherche \u00e0 compenser les capacit\u00e9s auditives avec le d\u00e9veloppement dans le domaine cognitif.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tr\u00e8s souvent par exemple les professeurs commencent \u00e0 apprendre aux \u00e9l\u00e8ves \u00e0 lire et \u00e0 \u00e9crire la musique, sans que leurs \u00e9l\u00e8ves aient acquit une exp\u00e9rience auditive et vocale concr\u00e8te du mouvement sonore et des diff\u00e9rentes hauteurs des sons. Les \u00e9l\u00e8ves plus dou\u00e9s font heureusement souvent cette liaison eux-m\u00eames, tout \u00e0 fait intuitivement. Ils lient les contenus des diff\u00e9rents domaines de l\u2019\u00e9ducation musicale qui sont sens\u00e9s travailler ensemble pour une compr\u00e9hension correcte des \u00e9l\u00e9ments musicaux. Mais cela ne se produit pas toujours automatiquement, loin s\u2019en faut, et dans les bases musicales apparaissent en cons\u00e9quence des lacunes et des points faibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour encourager le d\u00e9veloppement auditif sensoriel, Willems nous a pr\u00e9sent\u00e9 un grand nombre d\u2019excellentes directions et recommandations pour le travail avec les enfants.<br>D\u00e8s les premi\u00e8res le\u00e7ons les enfants d\u00e9couvrent, imitent, comparent, valorisent et mettent en ordre diff\u00e9rents sons, produits par les objets sonores et instruments divers. On cherche \u00e0 toucher leur curiosit\u00e9 et \u00e0 d\u00e9velopper leur int\u00e9r\u00eat pour le son, voire l\u2019amour du son. Dans son \u0153uvre \u00ab&nbsp;L\u2019oreille musicale&nbsp;\u00bb Willems a consacr\u00e9 beaucoup d\u2019espace \u00e0 la description pr\u00e9cise des instruments et leurs utilisations, qui permettent d\u00e9j\u00e0 aux tout-petits l\u2019acquisition d\u2019exp\u00e9riences dans le domaine des timbres sonores, de l\u2019intensit\u00e9 et surtout de la hauteur des sons et du mouvement sonore.&nbsp;<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" id=\"carillon-intratonal\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">L&rsquo;espace intratonal et le carillon intratonal<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Ses propositions incluent diff\u00e9rents objets sonores comme par exemple des cloches et des clochettes, des appeaux, des sifflets, des toupies chantantes et aussi des instruments sp\u00e9cifiques de haute valeur didactique comme la fl\u00fbte \u00e0 coulisse, la sir\u00e8ne, les tuyaux sonores, etc. Willems a explor\u00e9 aussi l\u2019espace intratonal, terme qu\u2019il a cr\u00e9\u00e9 \u2013 il \u00e9tait tr\u00e8s innovant dans ce domaine. Il avait diff\u00e9rentes collections de clochettes, y compris une collection de dix-sept clochettes qui \u00e9taient accord\u00e9es en 1\/16\u00e8 de ton dans la distance d\u2019un ton. Il a fabriqu\u00e9 un instrument sp\u00e9cial, l\u2019audiom\u00e8tre, avec lequel il a r\u00e9ussi \u00e0 produire les micro-intervalles jusqu\u2019au deux centi\u00e8me (1\/200e) du ton.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aujourd\u2019hui nous utilisons dans nos le\u00e7ons d\u2019\u00e9ducation musicale un \u00ab&nbsp;carillon intratonal&nbsp;\u00bb, avec lequel nous pouvons jouer des micro-diff\u00e9rences dans la hauteur des sons. Il est constitu\u00e9 de 24 plaques m\u00e9talliques visuellement parfaitement identiques, qui sont accord\u00e9es aux hauteurs du son diff\u00e9rentes dans l\u2019ambitus du G2 \u00e0 C3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cet instrument est utilis\u00e9 de diverses mani\u00e8res.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au <strong>premier degr\u00e9<\/strong> de l\u2019initiation, il peut \u00eatre employ\u00e9 pour r\u00e9aliser des glissandos, illustrant ainsi le mouvement sonore ascendant et descendant parcourant cet espace intratonal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au <strong>deuxi\u00e8me degr\u00e9<\/strong>, ce travail est approfondi : on peut fixer seulement quelques lames sur le bo\u00eetier auxiliaire de l\u2019instrument, par exemple celles permettant d\u2019ex\u00e9cuter des s\u00e9quences diatoniques ou chromatiques. Pendant le jeu avec les enfants, on intervertit deux lames quand ils ferment les yeux, et ils doivent r\u00e9tablir l\u2019ordre initial, uniquement gr\u00e2ce \u00e0 une \u00e9coute attentive. Ce principe p\u00e9dagogique est appel\u00e9 \u00ab pr\u00e9-classement \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au <strong>troisi\u00e8me degr\u00e9<\/strong>, dans la phase de \u00ab classement \u00bb, les lames sont compl\u00e8tement m\u00e9lang\u00e9es, et les \u00e9l\u00e8ves les remettent collectivement, puis individuellement dans le bon ordre. Cette m\u00e9thode est introduite en augmentant progressivement la difficult\u00e9 en s\u00e9lectionnant des lames formant des s\u00e9quences micro-intervalliques de plus en plus r\u00e9duites.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Willems a destin\u00e9 une place importante au travail dans l\u2019espace intratonal dans l\u2019\u00e9ducation musicale parce que la sensibilit\u00e9 de l\u2019oreille dans ce domaine am\u00e9liore non seulement l\u2019intonation, mais aussi la capacit\u00e9 de perception des structures musicales verticales (accords, agr\u00e9gats etc.). Il a ainsi \u00e9tabli diverses corr\u00e9lations : celui qui peut percevoir un huiti\u00e8me du ton, peut distinguer aussi les deux sons d\u2019un intervalle harmonique ; la perception des diff\u00e9rences de la hauteur des tons pour un seizi\u00e8me du ton correspond \u00e0 la capacit\u00e9 de distinguer les sons simultan\u00e9ment produits dans les accords de trois sons, etc. Il est aussi important d\u2019aiguiser l\u2019oreille dans le champ des structures musicales verticales \u2013 les \u00e9l\u00e8ves \u00e9coutent et chantent isol\u00e9ment les sons des intervalles harmoniques, des accords et des agr\u00e9gats.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9ceptivit\u00e9 sensorielle auditive est sans doute importante en tant que moyen de reconnaissance du son, elle n\u2019est toutefois pas la plus importante, puisque l\u2019essence de l\u2019art musical est ailleurs. Il est certain que la <strong>sensorialit\u00e9<\/strong> auditive repr\u00e9sente la base mat\u00e9rielle, \u00e0 partir de laquelle se d\u00e9veloppent la <strong>sensibilit\u00e9<\/strong> auditive et l\u2019<strong>intelligence<\/strong> auditive. Il s\u2019agit donc d\u2019assurer au son la place qui lui appartient dans l\u2019\u00e9ducation musicale, en tant que poutre\/support de l\u2019action musicale. On retrouve l\u00e0 les trois \u00e9tats de l\u2019\u00eatre humain : sensorialit\u00e9 pour sa dimension physique, sensibilit\u00e9 pour sa dimension affective, et intelligence pour sa dimension mentale.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" id=\"affectivit\u00e9-auditive\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">L\u2019affectivit\u00e9 auditive<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Avant de d\u00e9velopper ce chapitre, il convient de d\u00e9finir ce que peut \u00eatre l\u2019affectivit\u00e9 dans la nature humaine.<br>Je dirai que c\u2019est le si\u00e8ge de la sensibilit\u00e9, des \u00e9motions et de l\u2019humeur. Or tous ces \u00e9l\u00e9ments influencent l\u2019homme en provoquant chez lui une r\u00e9action physique, en r\u00e9action \u00e0 son environnement. Les psychologues aident leurs patients en contribuant \u00e0 d\u00e9m\u00ealer&nbsp; les n\u0153uds relationnels. Ce qui m\u2019am\u00e8ne \u00e0 <strong>associer l\u2019affectivit\u00e9 avec les relations \u00e0 autrui, et aussi \u00e0 soi-m\u00eame<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e8s lors, l\u2019affectivit\u00e9 auditive commence \u00e0 l\u2019instant de notre r\u00e9action au son, qui induit une relation au son. Il est impossible de d\u00e9finir exactement toutes les nuances de sensations, provoqu\u00e9es en nous par le son que nous entendons \u2013 son timbre, sa hauteur, son intensit\u00e9, sa dur\u00e9e et aussi bien s\u00fbr et surtout par les relations entre diff\u00e9rents sons, leur r\u00e9partition dans le temps, leurs hauteurs, leur dur\u00e9e et la vitesse de leurs encha\u00eenements. Ajoutons \u00e0 cet inventaire des combinaisons diff\u00e9rentes des qualit\u00e9s personnelles de l\u2019interpr\u00e8te de musique, de l\u2019auditeur et du compositeur, leur \u00e9tat d\u2019esprit, etc. \u2013 nous allons comprendre que l\u2019affectivit\u00e9 est un domaine difficile \u00e0 \u00e9valuer, un domaine subjectif, qui pourtant prend une place centrale dans l\u2019art, touchant \u00e0 l\u2019\u00e2me humaine l\u00e0 o\u00f9 rien d\u2019autre ne peut l\u2019atteindre, particuli\u00e8rement dans l\u2019art musical.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le c\u0153ur de l\u2019affectivit\u00e9 est la m\u00e9lodie, qui commence par les relations entre les sons, donc par l\u2019intervalle. Les intervalles m\u00e9lodiques portent en eux une charge \u00e9motive puissante. Willems l\u2019a largement d\u00e9crit dans la deuxi\u00e8me partie de son livre \u00ab&nbsp;L\u2019oreille musicale&nbsp;\u00bb. Il a analys\u00e9 les intervalles sous diff\u00e9rents points de vue : du point de vue quantitatif d\u2019abord, puis qualitatif. Dans une premi\u00e8re approche il s\u2019agit de diff\u00e9rents degr\u00e9s qui s\u00e9parent les deux sons de l\u2019intervalle ; dans la seconde il y va de la valeur affective de l\u2019intervalle \u2013 consonance, dissonance\u2026 Un m\u00eame intervalle peut avoir le mouvement ascendant ou descendant et ainsi obtenir deux qualit\u00e9s diff\u00e9rentes. Il peut \u00eatre positif ou n\u00e9gatif, par ex. l\u2019intervalle ascendant SOL \u2013 DO en Sol majeur repr\u00e9sente la relation entre un I<sup>er<\/sup> et un IV<sup>\u00e8me<\/sup> degr\u00e9, potentiellement Tonique et Sous-Dominante, et on l\u2019identifie comme Quarte positive. En Do majeur ce m\u00eame intervalle repr\u00e9sente la relation entre le V<sup>\u00e8me <\/sup>et le VIII<sup>\u00e8me<\/sup> degr\u00e9, possiblement Dominante et Tonique, et est identifi\u00e9 comme Quarte n\u00e9gative (Quarte comme renversement de la Quinte).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019intervalle a sa signification expressive, qui d\u00e9pend aussi de la place qu\u2019il occupe dans la gamme ou bien \u00e0 l\u2019int\u00e9rieur de la m\u00e9lodie&nbsp;; la Quarte positive de l\u2019exemple pr\u00e9c\u00e9dent signifie souvent le passage de la Tonique \u00e0 la Sous-Dominante, c\u2019est \u00e0 dire que la tension s\u2019intensifie et cro\u00eet&nbsp;; avec la Quarte n\u00e9gative par contre, c\u2019est le contraire&nbsp;: nous arrivons de la Dominante pour tomber sur la Tonique, la tension se r\u00e9sout et se calme.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La connaissance et la reconnaissance des intervalles occupe une place de grande importance dans l\u2019\u00e9ducation musicale suivant les principes p\u00e9dagogiques d&rsquo;Edgar Willems. Pour travailler sur ce domaine Willems propose entre autres l\u2019usage de chansons pour les intervalles. Ce sont des chansons qui commencent par un intervalle sp\u00e9cifique et leur propos didactique consiste \u00e0 en offrir aux \u00e9l\u00e8ves la connaissance des relations entre les sons. Le d\u00e9veloppement du sens m\u00e9lodique, qui a un r\u00f4le sup\u00e9rieur dans la musique, est encourag\u00e9 dans l\u2019\u00e9ducation musicale par la r\u00e9p\u00e9tition et l\u2019invention de motifs m\u00e9lodiques, la valorisation du potentiel expressif des intervalles, la connaissance approfondie des diff\u00e9rents modes et gammes, par l\u2019improvisation m\u00e9lodique, qui repr\u00e9sente un \u00e9l\u00e9ment important de la vie int\u00e9rieure, par l\u2019audition de la litt\u00e9rature musicale et bien s\u00fbr par les chansons chant\u00e9es et interpr\u00e9t\u00e9es sur les instruments.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Surtout le chant des chansons est tr\u00e8s important, puisque la chanson repr\u00e9sente la synth\u00e8se d\u2019un rythme, d\u2019une m\u00e9lodie, d\u2019une harmonie (par leur accompagnement) et d\u2019une histoire. Elles offrent beaucoup de possibilit\u00e9s pour travailler dans diff\u00e9rents domaines de l\u2019\u00e9ducation musicale. Les chansons, que les \u00e9l\u00e8ves ont apprises et qu\u2019ils connaissent bien, peuvent \u00eatre chant\u00e9es en vocalisant (sans les paroles) et transpos\u00e9es. Les deux d\u00e9marches aident \u00e0 d\u00e9velopper la m\u00e9moire m\u00e9lodique. L\u2019impr\u00e9gnation riche et vari\u00e9e est tr\u00e8s importante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous ne devons pas oublier la m\u00e9lodie libre, m\u00e9lodie qui na\u00eet en dehors de structures tonales m\u00e9lodiques traditionnelles. Nous ne les trouverons pas seulement dans la nature, mais aussi dans l\u2019art musical, surtout dans la musique contemporaine, qui cherche des nouvelles possibilit\u00e9s d\u2018expression (musique al\u00e9atoire, \u00e9lectronique, nouvelles techniques vocales et instrumentales&#8230;). La m\u00e9lodie libre d\u00e9place d\u2019une mani\u00e8re sp\u00e9ciale le point de gravit\u00e9 de l\u2019art musical auquel nous sommes habitu\u00e9s ailleurs \u2013 c\u2019est \u00e0 dire qu\u2019elle cherche les \u00e9l\u00e9ments d\u2019expression en-dehors des structures du syst\u00e8me tonal. Tous les \u00e9l\u00e9ments du langage musical, qui ne sont pas li\u00e9s \u00e0 la musique tonale, peuvent acqu\u00e9rir davantage de sens (timbre du son, dur\u00e9e, articulation, valeur expressive de l\u2019intervalle en soi).<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" id=\"intelligence-auditive\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">L\u2019intelligence auditive<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00e0 encore, il nous faut d\u00e9finir<em> a minima<\/em> ce qu\u2019on entend par intelligence.<br>L&rsquo;intelligence&nbsp;est l&rsquo;ensemble des processus trouv\u00e9s dans des&nbsp;syst\u00e8mes, plus ou moins&nbsp;complexes,&nbsp;vivants&nbsp;ou non, qui permettent d&rsquo;apprendre, de comprendre ou de s&rsquo;adapter \u00e0 des situations nouvelles. L&rsquo;intelligence a \u00e9t\u00e9 d\u00e9crite comme une facult\u00e9 d&rsquo;adaptation&nbsp;(apprentissage pour s&rsquo;adapter \u00e0 l&rsquo;environnement) ou au contraire, facult\u00e9 de modifier l&rsquo;environnement pour l&rsquo;adapter \u00e0 ses propres besoins. L&rsquo;acquisition de la parole articul\u00e9e et de l&rsquo;\u00e9criture, qui aident au d\u00e9veloppement du raisonnement et de l\u2019abstraction, font de l&rsquo;intelligence humaine la r\u00e9f\u00e9rence par rapport aux autres r\u00e8gnes de la nature.<br>Plut\u00f4t que de parler d&rsquo;intelligence, les psychologues pr\u00e9f\u00e8rent parler de fonctions sup\u00e9rieures d\u00e9finies de mani\u00e8re g\u00e9n\u00e9rique comme&nbsp;l&rsquo;aptitude des individus \u00e0 <strong>comprendre les relations<\/strong> qui existent entre diff\u00e9rents \u00e9l\u00e9ments d&rsquo;une situation et l&rsquo;aptitude \u00e0 s&rsquo;y adapter afin d&rsquo;atteindre ses propres objectifs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avoir de l&rsquo;intelligence auditive veut dire se rendre compte de diff\u00e9rents \u00e9l\u00e9ments de l\u2019art musical \u2013 c\u2019est d\u2019une grande importance et indispensable m\u00eame, si nous devons \u00eatre conscients du fait que l\u2019essence de l\u2019art fuit constamment la conscience. Nous ne pouvons par exemple pas expliquer d\u2019une mani\u00e8re rationnelle ce qui fait qu\u2019une \u0153uvre d\u2019art soit qualifi\u00e9e comme chef-d\u2019\u0153uvre. Nous pouvons cependant beaucoup dire d\u2019un chef-d\u2019\u0153uvre et l\u2019analyser, sa beaut\u00e9 et sa valeur expriment l\u2019\u00eatre humain dans son int\u00e9gralit\u00e9 et refl\u00e8tent le rapport de son auteur avec le monde, le rapport qui reste en grande partie incompr\u00e9hensible ou inexplicable et myst\u00e9rieux.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans l\u2019\u00e9ducation musicale, qui suit le principe : vie inconsciente \/ prise de conscience \/ vie consciente, ce passage qui m\u00e8ne de l\u2019inconscient au conscient est justement le point le plus sensible du processus. La pens\u00e9e peut effectivement mettre un obstacle \u00e0 la spontan\u00e9it\u00e9 et au naturel d\u2019un acte, surtout si on l\u2019introduit trop t\u00f4t. La pens\u00e9e n\u2019est pas la premi\u00e8re, elle vient plus tard ; la vie existe avant que la pens\u00e9e r\u00e9ussisse \u00e0 s\u2019y introduire. Spontan\u00e9it\u00e9 veut dire agir sans avoir planifi\u00e9, organis\u00e9, laiss\u00e9 que \u00e7a vienne tout seul \u2013 c\u2019est comme \u00e7a que commence la vie. Le mouvement rythmique corporel vient directement de la vie, c\u2019est la vie qui le fait na\u00eetre et qui le fa\u00e7onne. Nous pouvons l\u2019observer chez les animaux et aussi avec les petits enfants. La pens\u00e9e s\u2019aper\u00e7oit du mouvement, l\u2019aide \u00e0 devenir fonctionnel. Dans l\u2019art un mouvement deviendra encore plus coh\u00e9rent avec le contenu que l\u2019artiste veut transmettre \u00e0 l\u2019aide de la pens\u00e9e. Si la pens\u00e9e fait son intrusion trop t\u00f4t ou d\u2019une mani\u00e8re trop envahissante, le mouvement devient lourd et lent, artificiel, non plus li\u00e9 \u00e0 l\u2019\u00e9lan vital \u2013 cela peut arriver dans notre activit\u00e9 par exemple dans les mouvements, li\u00e9s \u00e0 la technique instrumentale.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre intention est donc que la pens\u00e9e, la sensibilit\u00e9 et l\u2019acte soient fusionn\u00e9s dans une unit\u00e9, qui rende possible l\u2019expression de la dimension mat\u00e9rielle et spirituelle de l\u2019art musical en une grande synth\u00e8se.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est tr\u00e8s important que l\u2019intelligence auditive, c&rsquo;est-\u00e0-dire la facult\u00e9 de <strong>d\u00e9nomination<\/strong>, d\u2019<strong>ordination<\/strong> et de <strong>compr\u00e9hension<\/strong> des contenus musicaux entendus et ressentis, ne soit pas confondue avec la connaissance intellectuelle du monde musical. La vraie intelligence auditive nous permet de rendre conscientes la sensorialit\u00e9 et l\u2019affectivit\u00e9 auditives ; c\u2019est comme \u00e7a qu\u2019ils deviennent deux \u00e9l\u00e9ments dont nous pouvons nous servir dans la pratique artistique, que ce soit l\u2019interpr\u00e9tation ou la cr\u00e9ation. La lecture et l\u2019\u00e9criture musicales, la connaissance th\u00e9orique des r\u00e8gles harmoniques et de composition, etc., ne doivent pas \u00eatre notre but en eux-m\u00eames, mais seulement des moyens de compr\u00e9hension et d\u2019expression de la pens\u00e9e musicale ; ils doivent donc toujours \u00eatre li\u00e9s au son. Il est parfaitement possible de \u201cconna\u00eetre\u201d un accord sans savoir comment est-ce qu\u2019il sonne et sans y r\u00e9agir affectivement. Il est aussi possible de composer de la musique \u00e0 la base de certaines r\u00e8gles, une musique qui n\u2019est pas l\u2019expression de la vie int\u00e9rieure de l\u2019homme. Il est clair que cela n\u2019a aucun lien avec le vrai art.<br><strong>L\u2019intelligence auditive comprend concr\u00e8tement les capacit\u00e9s de comparaison, valorisation, cr\u00e9ation, associations, analyse, synth\u00e8se, m\u00e9moire et imagination cr\u00e9ative.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au plan rythmique le proc\u00e9d\u00e9 de prise en conscience commence avec la d\u00e9nomination des \u00e9l\u00e9ments rythmiques (court \/ long et leurs combinaisons), plus tard c\u2019est la mesure, qui repr\u00e9sente l\u2019\u00e9l\u00e9ment de la prise en conscience, elle m\u00e8ne de l\u2019acte inconscient \u00e0 la lecture et \u00e0 l\u2019\u00e9criture de la musique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au plan m\u00e9lodique nous avons deux \u00e9l\u00e9ments d\u2019extr\u00eame importance, que Willems traite largement dans ses ouvrages : les noms de notes et les degr\u00e9s de la gamme. Bien s\u00fbr, nous commen\u00e7ons sur le plan m\u00e9lodique avec la d\u00e9nomination de diff\u00e9rents \u00e9l\u00e9ments aussi, le mouvement sonore, par exemple (monte \u2013 descend), les intervalles, etc.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le domaine de majeure expression de l\u2019intelligence auditive, apr\u00e8s la lecture et l\u2019\u00e9criture, est <strong>l\u2019harmonie<\/strong>, c&rsquo;est-\u00e0-dire la composante verticale de la musique et la connaissance des relations entre les accords.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme disait Carl Eitz, un p\u00e9dagogue allemand renomm\u00e9, les noms de notes sont comme des petits crochets, qui nous aident \u00e0 m\u00e9moriser les sons. Nous les introduisons tr\u00e8s t\u00f4t dans l\u2019\u00e9ducation musicale \u2013 d\u00e9j\u00e0 dans le 1er degr\u00e9 de l\u2019initiation comme des simples noms de sons, des onomatop\u00e9es en somme. Ils sont introduits d\u2019abord par les paroles de chansons, qui les contiennent, ensuite les paroles sont parfois remplac\u00e9es par les noms de sons. Les chansons en degr\u00e9s conjoints sont tr\u00e8s utiles. \u00c0 partir du 3<sup>\u00e8me<\/sup> degr\u00e9 d\u2019initiation nous travaillons d\u2019une mani\u00e8re dirig\u00e9e sur l\u2019association des sons et les noms des notes pour qu\u2019elle devienne la plus parfaite et naturelle possible, puisque cela facilite beaucoup l\u2019activit\u00e9 musicale. Grand nombre de principes de travail dans le 3<sup>\u00e8me<\/sup> et aussi bien s\u00fbr dans le 4<sup>\u00e8me<\/sup> degr\u00e9 est consacr\u00e9 justement \u00e0 cet objectif. Nous chantons les noms de notes dans les gammes, le cycle de la gamme diatonique Majeure, des ordonnances diverses, chansons, improvisations. L\u2019activit\u00e9 doit \u00eatre constante et consciente, le professeur doit la conduire avec patience, parce que le processus est long. Nous intensifions peu \u00e0 peu l\u2019exigence du travail. Tout cela se fait oralement, sans \u00e9crire une note. Mais l\u2019automatisation est aussi aid\u00e9e, bien s\u00fbr, par la lecture avec les noms de notes et l\u2019\u00e9criture (copie, transcription, transposition, dict\u00e9e, auto-dict\u00e9e, r\u00e9daction des propres inventions ou compositions des \u00e9l\u00e8ves).<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" id=\"solmisation-latine\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">Probl\u00e9matique de la solmisation latine compar\u00e9e \u00e0 l&rsquo;alphabet musical<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Willems a utilis\u00e9 la solmisation latine pour son approche p\u00e9dagogique.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le 3<sup>\u00e8me<\/sup> degr\u00e9 ou pr\u00e9paration au solf\u00e8ge comme l\u2019avait imagin\u00e9 Willems ne peut donc pas \u00eatre pratiqu\u00e9 avec l\u2019usage de l\u2019alphabet musical. Dans les milieux o\u00f9 l\u2019alphabet musical est pr\u00e9dominant, il est n\u00e9cessaire que les p\u00e9dagogues trouvent le chemin appropri\u00e9 et introduisent dans leur travail l\u2019alphabet musical au bon moment. \u00c0 partir de mes exp\u00e9riences personnelles je peux dire que c\u2019est r\u00e9alisable, mais que cela ralentit le processus d\u2019appropriation des noms de notes, comme le bilinguisme peut ralentir l\u2019acquisition d\u2019une langue maternelle.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quand j\u2019ai obtenu mon Dipl\u00f4me p\u00e9dagogique Willems<sup>\u00ae<\/sup> et ouvert mon \u00e9cole de musique en Slov\u00e9nie, j\u2019ai d\u00fb choisir la mani\u00e8re de nommer les sons que nous allions utiliser.<br>Car en Slov\u00e9nie l\u2019usage de l\u2019alphabet musical est pr\u00e9dominant, m\u00eame dans le chant. J\u2019ai d\u00e9cid\u00e9 finalement de me servir de la solmisation exclusivement pour l\u2019initiation musicale et pour le passage dans le 4<sup>\u00e8me<\/sup> degr\u00e9 j\u2019introduis l\u2019alphabet musical. Ensuite j\u2019utilise les deux syst\u00e8mes parall\u00e8lement, \u00e0 chaque le\u00e7on de solf\u00e8ge j\u2019effleure les deux. La solmisation est utilis\u00e9e r\u00e9guli\u00e8rement pour le chant et nous chantons avec l\u2019alphabet souvent aussi quand nous lisons. Quand nous traitons la th\u00e9orie musicale, je me sers exclusivement de l\u2019alphabet, puisqu\u2019il est plus pratique et plus clair.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019ai constat\u00e9 que les enfants qui au cours d\u2019ann\u00e9es apprennent \u00e0 ma\u00eetriser les relations tonales en lectures, dict\u00e9s et improvisation, n\u2019ont aucune difficult\u00e9 ni dans l\u2019un ni dans l\u2019autre syst\u00e8me, m\u00eame s\u2019ils r\u00e9agissent plus vite et mieux avec la solmisation. Les enfants qui ont des difficult\u00e9s pour ma\u00eetriser les intervalles, degr\u00e9s ou d\u2019autres \u00e9l\u00e9ments m\u00e9lodiques ont les m\u00eames probl\u00e8mes dans les deux syst\u00e8mes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La solution n\u2019est donc pas dans une ou l\u2019autre d\u00e9nomination mais dans un traitement approfondi des structures m\u00e9lodiques du langage musical.Comme les noms de notes, les degr\u00e9s aussi sont des symboles musicaux, mais ils trouvent leur place seulement un peu plus tard (depuis le 2<sup>\u00e8me<\/sup> degr\u00e9), puisqu\u2019ils sont plus abstraits. Willems nous a mis en garde de ne pas attribuer trop d\u2019importance aux degr\u00e9s au d\u00e9but de l\u2019apprentissage du solf\u00e8ge.<br>La premi\u00e8re association qu\u2019il nous faut travailler \u00e9tant : le son \/ le nom du son.&nbsp;<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" id=\"l\u2019harmonie\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">L&rsquo;harmonie<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les accords <\/strong>et <strong>l\u2019encha\u00eenement des accords<\/strong> repr\u00e9sentent le monde de <strong>l\u2019harmonie<\/strong>, dans lequel l\u2019intelligence auditive trouve sa plus forte expression. Les accords ont naturellement leur base mat\u00e9rielle et leur valeur sensible, mais la r\u00e9alit\u00e9 des accords et de l\u2019harmonie ne peut \u00eatre englob\u00e9e que par l\u2019intelligence, puisque l\u2019\u00e9l\u00e9ment caract\u00e9ristique de l\u2019harmonie est la simultan\u00e9it\u00e9, la synth\u00e8se, et que celle-ci pr\u00e9suppose l\u2019analyse.<br>La synth\u00e8se et l\u2019analyse sont essentiellement des fonctions mentales. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019intelligence devrait toujours \u00eatre li\u00e9e avec la sensorialit\u00e9 et l\u2019affectivit\u00e9. Dans le cas contraire nous allons retomber dans l\u2019enseignement th\u00e9orique au lieu de s\u2019occuper de l\u2019\u00e9ducation de l\u2019oreille et de la musique. L\u2019accord est donc, du point de vue sensoriel, l\u2019ensemble de trois sons (minimum 3). Du point de vue affectif, il est l&rsquo;ensemble de deux intervalles minimum dont on analysera les relations deux \u00e0 deux, tandis que du point de vue intellectuel il repr\u00e9sente une&nbsp; fonction mentale, sa dimension plus importante.<br>Cette fonction r\u00e8gle notamment les encha\u00eenements des accords, et avec eux l\u2019harmonie.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aupr\u00e8s des musiciens de grande qualit\u00e9 il y a une quatri\u00e8me dimension qui est exprim\u00e9e, c\u2019est l\u2019intuition. L\u2019intuition peut se trouver dans tous les domaines de la musique, mais elle trouve \u2013 telle une facult\u00e9 humaine supra-mentale de la synth\u00e8se au plus haut niveau \u2013 son r\u00f4le crucial dans l\u2019encha\u00eenement des accords, l\u2019harmonie et la composition. L\u2019harmonie mat\u00e9rielle, repr\u00e9sent\u00e9e par la simultan\u00e9it\u00e9 des sons, atteint dans l\u2019art \u2013 \u00e0 travers l\u2019intuition \u2013 le niveau spirituel dans l\u2019int\u00e9gralit\u00e9, ou bien dans l\u2019unit\u00e9 du rythme, de la m\u00e9lodie et de l&rsquo;harmonie.&nbsp;<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" id=\"developpement-du-chant\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">LE D\u00c9VELOPPEMENT DU CHANT<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Avant de parler du chant, il convient de pr\u00e9senter le fonctionnement de l\u2019organe phonatoire. Car sans entrer dans le d\u00e9tail de la vaste probl\u00e9matique de la technique vocale, il est important pour tout p\u00e9dagogue musical de conna\u00eetre <em>a minima<\/em> le fonctionnement des cordes vocales. En voici donc une description succincte.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"fonctionnement-des-cordes-vocales\">Description simple du fonctionnement des cordes vocales<\/h5>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Les cordes vocales sont situ\u00e9es dans le larynx, \u00e0 la hauteur de la gorge.<br>Ce sont deux bandes musculaires souples, tendues comme des \u00e9lastiques.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"468\" height=\"506\" src=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-5.png\" alt=\"\" class=\"wp-image-5023 size-full\" srcset=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-5.png 468w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-5-277x300.png 277w\" sizes=\"auto, (max-width: 468px) 100vw, 468px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"478\" height=\"406\" src=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-6.png\" alt=\"\" class=\"wp-image-5024 size-full\" srcset=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-6.png 478w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-6-300x255.png 300w, https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/image-6-281x239.png 281w\" sizes=\"auto, (max-width: 478px) 100vw, 478px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Pendant la respiration normale, les cordes vocales sont ouvertes pour laisser passer l\u2019air sans son. Pour produire des sons, les cordes vocales se rapprochent et se tendent. L\u2019air des poumons passe entre elles et les fait vibrer.&nbsp;<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ce sont ces vibrations qui produisent un son brut. La tension, l\u2019\u00e9paisseur et la vitesse de vibration modifient la hauteur (grave ou aigu) et le timbre du son. Ensuite, la bouche, la langue et les l\u00e8vres fa\u00e7onnent ce son brut pour former des mots, des sons pr\u00e9cis et bien s\u00fbr un chant !&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><a href=\"https:\/\/youtu.be\/U75BHAOxWt0?si=6qw_Hhvbp8nRevt2\">Vid\u00e9o des cordes vocales en action.<\/a><\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" id=\"relation-oreille-voix\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">La relation entre l\u2019oreille et la voix<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019oreille est l\u2019\u00e9l\u00e9ment de r\u00e9ception et de formation des informations qui se traduisent dans notre cerveau comme son. La voix repr\u00e9sente l\u2019expression humaine la plus importante tout en identifiant la personne, puisque chaque homme a une voix unique.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque nous parlons de l\u2019oreille et de la voix, nous parlons donc de la r\u00e9ception du son et de l\u2019expression \u00e0 travers le son, de la base du langage musical et de l\u2019art musical.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Willems cite Wagner dans la deuxi\u00e8me partie de ses bases psychologiques :<br><strong>\u201c<\/strong><strong><em>Le chant, le chant et encore le chant. Le chant est une fois pour toutes le langage par lequel l\u2019homme communique avec l\u2019autre d\u2019une mani\u00e8re musicale\u2026 L\u2019instrument le plus ancien, le plus vrai et le plus beau est la voix humaine, c\u2019est \u00e0 elle que la musique doit son existence.<\/em><\/strong><strong>\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Willems a mis bien en valeur l\u2019importance du d\u00e9veloppement de l\u2019oreille et de la voix dans la premi\u00e8re \u00e9ducation musicale. C\u2019est seulement quand l\u2019enfant aura appris \u00e0 \u00e9couter et s\u2019exprimer musicalement \u00e0 travers la voix \u2013 en musique cela veut dire surtout \u00e0 travers le chant \u2013 qu\u2019il sera vraiment pr\u00eat \u00e0 s\u2019occuper du solf\u00e8ge et de l\u2019instrument. \u00c0 travers l\u2019instrument, l\u2019enfant peut alors s\u2019exprimer diff\u00e9remment de ce qu\u2019il peut exprimer par la voix. L\u2019instrument est une extension de la voix humaine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quand nous travaillons dans le domaine de l\u2019\u00e9ducation musicale, nous souhaitons que l\u2019enfant d\u00e9veloppe une voix naturelle, chaleureuse, juste dans l\u2019intonation et d\u2019une articulation pr\u00e9cise, par laquelle il pourra exprimer sa vie musicale int\u00e9rieure. Dans l\u2019acte de chanter le corps entier participe. La posture et la respiration sont importantes \u2013 en expirant la voix passe \u00e0 travers les cordes vocales, la cavit\u00e9 buccale et nasale, qui sont importantes pour l\u2019articulation et la r\u00e9sonance (amplification) du son. Chaque changement dans l\u2019espace agit sur la formation du son \u2013 soit de l\u2019espace o\u00f9 le son rencontre \u00e0 l\u2019int\u00e9rieur du corps soit de celui qui se trouve \u00e0 l\u2019ext\u00e9rieur. Un \u00e9l\u00e9ment important pour le chant est le diaphragme, muscle qui s\u00e9pare la partie abdominale (du syst\u00e8me digestif) de la poitrine et des poumons ; c\u2019est par lui que le flux d\u2019air est r\u00e9gl\u00e9. Les cordes vocales sont situ\u00e9es dans la gorge. Ce sont deux plis fins, \u00e9lastiques, couverts de mucus qui se trouvent en position horizontale. La hauteur du son, produit par les cordes vocales en vibration, provoqu\u00e9e par le passage de l\u2019air, d\u00e9pend de leur longueur et de leur \u00e9paisseur. Quand on parle ou chante, les cordes vocales sont tendues \u2013 c\u2019est le r\u00e9sultat du travail des muscles qui r\u00e8glent leur tension.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La voix a une part importante dans toutes les le\u00e7ons d\u00e8s le 1<sup>er<\/sup> degr\u00e9 d\u2019initiation musicale. Le premier principe de la premi\u00e8re partie de la le\u00e7on a pour but le d\u00e9veloppement auditif sensoriel et affectif, mais &#8211; j\u2019ajoute : toujours en liaison avec le d\u00e9veloppement vocal \u2013 c\u2019est l\u2019\u00e9coute et la production du mouvement sonore panchromatique et diatonique. Pour une pr\u00e9sentation claire et la cr\u00e9ation des associations utiles, nous nous servons des instruments, qui montrent le mouvement sonore aussi d\u2019une mani\u00e8re visuelle \u2013 ce sont surtout la fl\u00fbte \u00e0 coulisse, le xylophone et le carillon. Nous utilisons en plus la sir\u00e8ne, qui a un son plus doux, plus rond, avec laquelle le mouvement sonore n\u2019est plus visible. Les enfants \u00e9coutent et imitent les mouvements sonores avec leur voix. Il est important que l\u2019attention de l\u2019enfant soit toujours guid\u00e9e vers l\u2019\u00e9coute de l\u2019instrument ou de la voix du professeur et de sa propre voix.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les enfants inventent eux-aussi des mouvements sonores, explorent activement la hauteur du son, et en pratiquant toutes sortes de glissandi, \u00e9largissent leur tessiture vocale. Nous accompagnons notre chant avec la main, qui montre dans l\u2019espace le mouvement sonore ascendant ou descendant, permettant de concr\u00e9tiser visuellement les notions de mont\u00e9e et de descente. D\u2019une mani\u00e8re similaire nous travaillons aussi dans le champ des sons graves, m\u00e9dium ou aigus isol\u00e9s. M\u00eame si la hauteur du son est la plus importante, nous dirigeons lors des imitations l\u2019attention de l\u2019enfant aussi vers la dur\u00e9e et le timbre. L\u2019enfant reconna\u00eet en \u00e9coutant diff\u00e9rents \u00e9metteurs et \u00e9l\u00e9ments du son qu\u2019il imite avec sa voix, c\u2019est comme \u00e7a qu\u2019il apprend aussi \u00e0 conna\u00eetre sa propre voix et \u00e0 l\u2019utiliser.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En r\u00e9p\u00e9tant et inventant des intervalles m\u00e9lodiques, nous entrons dans le d\u00e9veloppement auditif affectif, dans lequel r\u00e8gnent les relations entre les sons. Ici aussi nous pouvons nous aider avec diff\u00e9rents instruments (comme les coucous et appeaux divers). Pour l\u2019imitation et invention des motifs m\u00e9lodiques c\u2019est la voix qui est au premier plan \u2013 chez le professeur comme chez l\u2019\u00e9l\u00e8ve. La r\u00e9p\u00e9tition et l\u2019invention sont pratiqu\u00e9es en groupe comme individuellement, dans une bonne proportion avec le sentiment de s\u00e9curit\u00e9 en groupe. La pratique d\u2019ensemble rend possible une r\u00e9alisation plus assur\u00e9e et plus tranquille ; tandis que la v\u00e9rification individuelle des enfants est aussi n\u00e9cessaire pour pouvoir avancer dans la justesse de l\u2019intonation individuelle, pour faire un beau legato et r\u00e9v\u00e9ler la beaut\u00e9 de la voix de chacun. L\u2019enfant participe aussi vocalement quand on utilise les tuyaux sonores \u2013 l\u2019association de la force physique des muscles qui font tourner le tuyau et produisent les harmoniques aigus, et le chant de ces harmoniques est une exp\u00e9rience pr\u00e9cieuse pour l\u2019enfant. Nous \u00e9tablissons ce faisant un lien entre l\u2019\u00e9nergie investie et la hauteur du son qui est essentielle dans le chant.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La voix trouve sa place \u00e9galement dans la deuxi\u00e8me partie de la le\u00e7on, consacr\u00e9e au d\u00e9veloppement du sens rythmique. Avec la voix nous amplifions souvent les battements des rythmes avec les mains sur la table o\u00f9 des mouvements du corps entier (sauts, tape des mains,..) \u2013 le plus souvent en utilisant les onomatop\u00e9es. Nous pouvons quelquefois nous servir aussi des mots \u2013 nous r\u00e9alisons alors le rythme du langage parl\u00e9 en tapant avec les mains sur la table, puisque la langue parl\u00e9e est une des sources importantes du rythme. De cette mani\u00e8re le lien entre l\u2019oreille et le mouvement rythmique du corps est encore plus stimul\u00e9, la voix \u00e9tant une amplification de l\u2019effet sonore du corps en mouvement qui am\u00e9liore la coordination entre l\u2019oreille, le cerveau et le mouvement physique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La voix prend le r\u00f4le central dans la troisi\u00e8me partie de la le\u00e7on, consacr\u00e9e au chant des chansons. Les chansons sont extr\u00eamement importantes pour la rencontre entre l\u2019enfant et la musique, parce qu\u2019elles repr\u00e9sentent une exp\u00e9rience musicale compl\u00e8te, dans laquelle l\u2019enfant peut participer activement comme interpr\u00e8te. Elles relient la m\u00e9lodie, le rythme, l\u2019harmonie et l\u2019histoire dans une unit\u00e9 musicale en faisant induire et sentir \u00e0 l\u2019enfant la connexion et l\u2019interd\u00e9pendance des diff\u00e9rents \u00e9l\u00e9ments musicaux.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le choix des chansons que nous utilisons en travaillant avec les enfants doit \u00eatre men\u00e9 tr\u00e8s soigneusement et professionnellement. C\u2019est important parce que les chansons repr\u00e9sentent un point fort, peut-\u00eatre le plus important de l\u2019impr\u00e9gnation que nous offrons aux \u00e9l\u00e8ves. Elles doivent \u00eatre adapt\u00e9es et inspirantes tant du point de vue musical que pour leurs paroles. Nous devons savoir que le choix des chansons comprend aussi un aspect culturel, les chansons \u00e9tant le reflet de notre histoire, notre langue, religion, mani\u00e8re de vivre. C\u2019est pourquoi les chansons populaires ont un sens particulier. En utilisant les chansons \u00e9trang\u00e8res avec lesquelles nous enrichissons notre r\u00e9pertoire, il faut faire attention \u00e0 la traduction de qualit\u00e9 et conserver l&rsquo;authenticit\u00e9 de la chanson, tenir compte de la prosodie, de la concordance entre les paroles, la phrase musicale et la rime. Nous sommes attentifs aussi \u00e0 tous ces \u00e9l\u00e9ments quand nous choisissons les chansons d\u2019auteur, puisque toutes ne sont pas de la m\u00eame qualit\u00e9. Il y en a aussi qui ont une valeur p\u00e9dagogique \u2013 nous utilisons beaucoup les chansons de deux \u00e0 cinq notes, qui ont un ambitus plus petit et sont tr\u00e8s appropri\u00e9es plus tard pour les d\u00e9buts instrumentaux&nbsp;; les chansons d\u2019intervalles et d\u2019accords&nbsp;; chansons int\u00e9ressantes pour leurs contenus rythmiques et chansons qui contiennent les noms de notes dans les paroles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En pratiquant ces chansons nous faisons attention \u00e0 un beau phras\u00e9, une prononciation claire, une respiration naturelle, au l\u00e9gato et \u00e0 l\u2019articulation. Quand nous accompagnons les chansons avec les instruments rythmiques, nous ne devons pas retomber dans la syllabation, que nous entendons malheureusement souvent dans les cr\u00e8ches, maternelles et \u00e9coles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019enfant peut \u00e9galement participer avec sa voix dans la s\u00e9quence du mouvement corporel naturel ; il peut par exemple chanter la m\u00e9lodie des compositions que le professeur propose plusieurs fois comme point de d\u00e9part pour le mouvement ou en chantant les chansons qui sont propices pour cette pratique. De cette fa\u00e7on l\u2019enfant r\u00e9alise le chant et les mouvements, qui sont coordonn\u00e9s, il accorde la r\u00e9alisation des modes rythmiques, par exemple&nbsp;: le rythme en chantant, le tempo en marchant, la mesure, la division ou un ostinato dans les mains. C\u2019est comme cela qu\u2019on installe les connections entre l\u2019oreille, le corps dans le mouvement et le cerveau, tandis que du point de vue musical il s\u2019agit d\u2019associer les diff\u00e9rents \u00e9l\u00e9ments dans un tout harmonieux, \u00e9quilibr\u00e9 et artistique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le deuxi\u00e8me degr\u00e9 de l\u2019initiation musicale l\u2019enfant est d\u00e9j\u00e0 habitu\u00e9 \u00e0 l\u2019expression vocale \u00e0 travers le chant. Il peut jusqu\u2019\u00e0 un certain point ma\u00eetriser sa voix, sait produire diff\u00e9rents mouvements sonores, imiter diff\u00e9rents instruments, r\u00e9p\u00e9ter la hauteur d\u2019un son isol\u00e9 et inventer les sons de hauteurs diff\u00e9rentes. Au plan rythmique il a acquis la relation basique entre le geste et le son et sait diriger son \u00e9nergie physique dans la production des rythmes simples. Il conna\u00eet beaucoup de chansons et ressent la r\u00e9gularit\u00e9 ou bien la pulsation de la musique qu\u2019il \u00e9coute, en pouvant accorder avec elle le mouvement de son corps. C\u2019est pourquoi nous pouvons poursuivre en ajoutant progressivement aux \u00e9l\u00e9ments acquis les graphismes des contenus sonores et rythmiques, les noms de notes et d\u2019autres contenus du 2<sup>\u00e8me<\/sup> degr\u00e9. L\u2019introduction du graphisme est toujours accompagn\u00e9e par l\u2019expression vocale, jusqu\u2019\u00e0 ce que nous soyons certains que l\u2019enfant produit le graphisme \u00e0 partir de l\u2019audition int\u00e9rieure.&nbsp;<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" id=\"conclusion\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">CONCLUSION<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019audition int\u00e9rieure, qui est tellement importante pour tous les musiciens et dont j\u2019ai parl\u00e9 au d\u00e9but, est form\u00e9e justement \u00e0 la base du chant, et celui-ci est li\u00e9 avec l\u2019oreille musicale bien d\u00e9velopp\u00e9e. C\u2019est pourquoi le chant a un tr\u00e8s grand r\u00f4le tout au long de l\u2019\u00e9ducation musicale, m\u00eame quand l\u2019enfant, le 3<sup>\u00e8me<\/sup> degr\u00e9 termin\u00e9 (la pr\u00e9paration au solf\u00e8ge et \u00e0 l\u2019instrument), entreprend le solf\u00e8ge vivant et l\u2019apprentissage du jeu instrumental.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Willems a mis en \u00e9vidence dans ses \u0153uvres l\u2019importance du chant, qui permet un contact vivant avec la musique en sa totalit\u00e9. Le chant offre aux enfants une exp\u00e9rience musicale riche et active, li\u00e9e au rythme, la m\u00e9lodie et l\u2019harmonie de la chanson. Par la chanson l\u2019enfant, qui est en grande partie un \u00eatre \u00e9motif, peut rencontrer diff\u00e9rentes sensations et \u00e9motions, les individualiser \u00e0 l\u2019aide de la musique et les reconna\u00eetre en soi-m\u00eame et ses compagnons. La voix est donc un moyen important de rencontre entre l\u2019enfant et la musique dans toutes les trois dimensions \u2013 physiologique, affective et mentale. Elle est aussi un \u00e9l\u00e9ment puissant d\u2019association, prise de conscience et coordination des contenus, savoirs et savoir-faire en musique. Nous ne devons pas oublier que l\u2019expression vocale et le chant doivent \u00eatre li\u00e9s \u00e0 l&rsquo;oreille musicalement \u00e9lev\u00e9e (\u00e9duqu\u00e9e) \u2013 c\u2019est la seule garantie d\u2019une base musicale r\u00e9elle pour le d\u00e9veloppement d\u2019un bon musicien, qui pourra <em>entendre<\/em> la musique et la r\u00e9aliser avec une tr\u00e8s haute qualit\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sources : les \u0153uvres d\u2019Edgar Willems<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec mes remerciements \u00e0 Christophe Lazerges pour sa relecture et les traductions.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9veloppement de l&rsquo;oreille musicale et du chant dans l\u2019\u00e9ducation musicale Willems\u00ae Mateja Tomac Calligaris &#8211; M\u00e9moire Didactique Willems\u00ae Voici le m\u00e9moire r\u00e9dig\u00e9 en 2023 pour son Dipl\u00f4me Didactique Willems\u00ae&nbsp;par &hellip;<\/p>\n","protected":false},"author":1,"featured_media":5000,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"class_list":["post-4998","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le d\u00e9veloppement auditif et vocal - Pigyki<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pigyki.fr\/index.php\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le d\u00e9veloppement auditif et vocal - Pigyki\" \/>\n<meta property=\"og:description\" content=\"Le d\u00e9veloppement de l&rsquo;oreille musicale et du chant dans l\u2019\u00e9ducation musicale Willems\u00ae Mateja Tomac Calligaris &#8211; M\u00e9moire Didactique Willems\u00ae Voici le m\u00e9moire r\u00e9dig\u00e9 en 2023 pour son Dipl\u00f4me Didactique Willems\u00ae&nbsp;par &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pigyki.fr\/index.php\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\/\" \/>\n<meta property=\"og:site_name\" content=\"Pigyki\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-12T21:07:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/Enfant-oreilles-et-bouche-ouvertes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"279\" \/>\n\t<meta property=\"og:image:height\" content=\"156\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"42 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\\\/\",\"url\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\\\/\",\"name\":\"Le d\u00e9veloppement auditif et vocal - Pigyki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Enfant-oreilles-et-bouche-ouvertes.jpg\",\"datePublished\":\"2025-05-04T21:23:27+00:00\",\"dateModified\":\"2025-07-12T21:07:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Enfant-oreilles-et-bouche-ouvertes.jpg\",\"contentUrl\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Enfant-oreilles-et-bouche-ouvertes.jpg\",\"width\":279,\"height\":156},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pigyki.fr\\\/index.php\\\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/pigyki.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le d\u00e9veloppement auditif et vocal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pigyki.fr\\\/#website\",\"url\":\"https:\\\/\\\/pigyki.fr\\\/\",\"name\":\"Pigyki\",\"description\":\"C.L. al fine\",\"publisher\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/#\\\/schema\\\/person\\\/0c57b3ed8707391e1213001f02e0ef84\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pigyki.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/pigyki.fr\\\/#\\\/schema\\\/person\\\/0c57b3ed8707391e1213001f02e0ef84\",\"name\":\"Pigyki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Logo-CL.jpg\",\"url\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Logo-CL.jpg\",\"contentUrl\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Logo-CL.jpg\",\"width\":524,\"height\":586,\"caption\":\"Pigyki\"},\"logo\":{\"@id\":\"https:\\\/\\\/pigyki.fr\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Logo-CL.jpg\"},\"sameAs\":[\"http:\\\/\\\/pigyki.fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le d\u00e9veloppement auditif et vocal - Pigyki","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pigyki.fr\/index.php\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\/","og_locale":"fr_FR","og_type":"article","og_title":"Le d\u00e9veloppement auditif et vocal - Pigyki","og_description":"Le d\u00e9veloppement de l&rsquo;oreille musicale et du chant dans l\u2019\u00e9ducation musicale Willems\u00ae Mateja Tomac Calligaris &#8211; M\u00e9moire Didactique Willems\u00ae Voici le m\u00e9moire r\u00e9dig\u00e9 en 2023 pour son Dipl\u00f4me Didactique Willems\u00ae&nbsp;par &hellip;","og_url":"https:\/\/pigyki.fr\/index.php\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\/","og_site_name":"Pigyki","article_modified_time":"2025-07-12T21:07:37+00:00","og_image":[{"width":279,"height":156,"url":"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/Enfant-oreilles-et-bouche-ouvertes.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"42 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pigyki.fr\/index.php\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\/","url":"https:\/\/pigyki.fr\/index.php\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\/","name":"Le d\u00e9veloppement auditif et vocal - Pigyki","isPartOf":{"@id":"https:\/\/pigyki.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pigyki.fr\/index.php\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\/#primaryimage"},"image":{"@id":"https:\/\/pigyki.fr\/index.php\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\/#primaryimage"},"thumbnailUrl":"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/Enfant-oreilles-et-bouche-ouvertes.jpg","datePublished":"2025-05-04T21:23:27+00:00","dateModified":"2025-07-12T21:07:37+00:00","breadcrumb":{"@id":"https:\/\/pigyki.fr\/index.php\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pigyki.fr\/index.php\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pigyki.fr\/index.php\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\/#primaryimage","url":"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/Enfant-oreilles-et-bouche-ouvertes.jpg","contentUrl":"https:\/\/pigyki.fr\/wp-content\/uploads\/2025\/05\/Enfant-oreilles-et-bouche-ouvertes.jpg","width":279,"height":156},{"@type":"BreadcrumbList","@id":"https:\/\/pigyki.fr\/index.php\/le-developpement-de-loreille-musicale-et-du-chant-dans-leducation-musicale-willems\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/pigyki.fr\/"},{"@type":"ListItem","position":2,"name":"Le d\u00e9veloppement auditif et vocal"}]},{"@type":"WebSite","@id":"https:\/\/pigyki.fr\/#website","url":"https:\/\/pigyki.fr\/","name":"Pigyki","description":"C.L. al fine","publisher":{"@id":"https:\/\/pigyki.fr\/#\/schema\/person\/0c57b3ed8707391e1213001f02e0ef84"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pigyki.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/pigyki.fr\/#\/schema\/person\/0c57b3ed8707391e1213001f02e0ef84","name":"Pigyki","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/06\/Logo-CL.jpg","url":"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/06\/Logo-CL.jpg","contentUrl":"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/06\/Logo-CL.jpg","width":524,"height":586,"caption":"Pigyki"},"logo":{"@id":"https:\/\/pigyki.fr\/wp-content\/uploads\/2023\/06\/Logo-CL.jpg"},"sameAs":["http:\/\/pigyki.fr"]}]}},"_links":{"self":[{"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/pages\/4998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/comments?post=4998"}],"version-history":[{"count":23,"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/pages\/4998\/revisions"}],"predecessor-version":[{"id":5781,"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/pages\/4998\/revisions\/5781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/media\/5000"}],"wp:attachment":[{"href":"https:\/\/pigyki.fr\/index.php\/wp-json\/wp\/v2\/media?parent=4998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}